{"id":1165,"count":1,"description":"","link":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/","name":"Zana Bilir Kaya","slug":"zana-bilir-kaya","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zana Bilir Kaya ar\u015fivleri - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zana Bilir Kaya ar\u015fivleri - International Journalists\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/tag\\\/zana-bilir-kaya\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/tag\\\/zana-bilir-kaya\\\/\",\"name\":\"Zana Bilir Kaya ar\u015fivleri - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/tag\\\/zana-bilir-kaya\\\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/tag\\\/zana-bilir-kaya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zana Bilir Kaya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zana Bilir Kaya ar\u015fivleri - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/","og_locale":"tr_TR","og_type":"article","og_title":"Zana Bilir Kaya ar\u015fivleri - International Journalists","og_url":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/","og_site_name":"International Journalists","twitter_card":"summary_large_image","twitter_site":"@journalists_tr","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/","url":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/","name":"Zana Bilir Kaya ar\u015fivleri - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/tr\/tag\/zana-bilir-kaya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/tr\/"},{"@type":"ListItem","position":2,"name":"Zana Bilir Kaya"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/tr\/#website","url":"https:\/\/internationaljournalists.org\/tr\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/tr\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/internationaljournalists.org\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]}]}},"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/tr\/wp-json\/wp\/v2\/tags\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/internationaljournalists.org\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/internationaljournalists.org\/tr\/wp-json\/wp\/v2\/posts?tags=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}