{"id":40149,"date":"2025-05-30T07:24:31","date_gmt":"2025-05-30T05:24:31","guid":{"rendered":"https:\/\/ijaev.org\/?p=40149"},"modified":"2025-05-30T07:24:31","modified_gmt":"2025-05-30T05:24:31","slug":"zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/","title":{"rendered":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1"},"content":{"rendered":"<p>Der Druck auf kritische Medien in der T\u00fcrkei nimmt weiter zu. Die Rundfunk- und Fernsehaufsichtsbeh\u00f6rde (RT\u00dcK) setzt ihre Linie der Zensur und Repression fort und hat erneut Ma\u00dfnahmen gegen oppositionelle Fernsehsender verh\u00e4ngt. S\u00f6zc\u00fc TV wurde mit einem zehnt\u00e4gigen Sendeverbot belegt, w\u00e4hrend Halk TV und TELE1 mit Geldstrafen belegt wurden.<\/p>\n<h2>Sendeverbot f\u00fcr S\u00f6zc\u00fc TV<\/h2>\n<p>Grundlage f\u00fcr die Entscheidung gegen S\u00f6zc\u00fc TV war die Berichterstattung \u00fcber ein laufendes Ermittlungsverfahren gegen den Istanbuler B\u00fcrgermeister und Pr\u00e4sidentschaftskandidaten der CHP, Ekrem \u0130mamo\u011flu. In den Live-Sendungen des Senders w\u00e4hrend der Ermittlungen habe man laut RT\u00dcK zur \u201eAnstiftung zu Hass und Feindseligkeit\u201c beigetragen.<\/p>\n<p>RT\u00dcK teilte dem Sender offiziell mit, dass er ab dem 1. Juni f\u00fcr zehn Tage den Sendebetrieb einstellen m\u00fcsse. Beobachter werten dies als eine der schwerwiegendsten Strafen vor einem m\u00f6glichen Lizensierungsentzug.<\/p>\n<h2>Geldstrafen gegen Halk TV und TELE1<\/h2>\n<p>Auch andere oppositionelle Sender wurden in derselben RT\u00dcK-Sitzung sanktioniert. Halk TV erhielt zwei Geldstrafen, TELE1 eine. Tuncay Keser, RT\u00dcK-Mitglied aus dem CHP-Kontingent, erkl\u00e4rte, dass die Strafen vor allem auf Beschwerden des Bauunternehmens Ta\u015fyap\u0131 zur\u00fcckzuf\u00fchren seien. Er warf der Beh\u00f6rde vor, die Interessen des Unternehmens zu sch\u00fctzen und kritische Berichterstattung zu sanktionieren.<\/p>\n<p>Die erste Geldstrafe gegen Halk TV betraf die Sendung \u201eA\u00e7\u0131k\u00e7a\u201c, in der Aussagen \u00fcber angebliche Verbindungen von Managern der Stadt Istanbul und des Bezirks \u015ei\u015fli zu kriminellen Strukturen thematisiert wurden. Aufgrund der ge\u00e4u\u00dferten Kritik verh\u00e4ngte RT\u00dcK eine Verwaltungsstrafe in H\u00f6he von 3 Prozent des Monatseinkommens.<\/p>\n<p>Eine zweite Strafe erhielt der Sender f\u00fcr die Sendung \u201eNeden Sonu\u00e7\u201c, in der Journalist \u0130brahim Kahveci erkl\u00e4rte: \u201eDiese Regierung liebt die Wissenschaft nicht, die Naturwissenschaften nicht. An den Universit\u00e4ten gibt es keine Qualit\u00e4t mehr. Man bildet \u00c4rzte aus, die nie eine Leiche gesehen haben.\u201c Auch diese Aussagen wurden von RT\u00dcK als strafw\u00fcrdig eingestuft.<\/p>\n<h2>TELE1 im Visier wegen Kritik an RT\u00dcK und Banken<\/h2>\n<p>TELE1 wurde f\u00fcr kritische Aussagen des Moderators Musa \u00d6zu\u011furlu \u00fcber die Werbepolitik von RT\u00dcK und staatlichen Banken ebenfalls mit einer Geldstrafe von 3 Prozent belegt.<\/p>\n<h2>Systematische Repression gegen oppositionelle Medien<\/h2>\n<p>Diese j\u00fcngsten Sanktionen zeigen erneut, wie systematisch oppositionelle Medien in der T\u00fcrkei unter Druck gesetzt werden. Die Ma\u00dfnahmen gegen S\u00f6zc\u00fc TV, Halk TV und TELE1 verdeutlichen den besorgniserregenden Zustand der Medienfreiheit im Land. Kritische Stimmen sehen sich einer wachsenden Zensur gegen\u00fcber, w\u00e4hrend regierungsnahe Medien von solchen Eingriffen verschont bleiben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Druck auf kritische Medien in der T\u00fcrkei nimmt weiter zu. Die Rundfunk- und Fernsehaufsichtsbeh\u00f6rde (RT\u00dcK) setzt ihre Linie der Zensur und Repression fort und hat erneut Ma\u00dfnahmen gegen oppositionelle Fernsehsender verh\u00e4ngt. S\u00f6zc\u00fc TV wurde mit einem zehnt\u00e4gigen Sendeverbot belegt, w\u00e4hrend Halk TV und TELE1 mit Geldstrafen belegt wurden. Sendeverbot f\u00fcr S\u00f6zc\u00fc TV Grundlage f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":40150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","override":[{"template":"1","parallax":"1","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_reading_time":"0","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_popup_post":"1","number_popup_post":"2"}],"image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4623,2868,4678],"tags":[],"class_list":["post-40149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","category-schlagzeile","category-medya-hak-ihlal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Der Druck auf kritische Medien in der T\u00fcrkei nimmt weiter zu. Die Rundfunk- und Fernsehaufsichtsbeh\u00f6rde (RT\u00dcK) setzt ihre Linie der Zensur und Repression fort und hat erneut Ma\u00dfnahmen gegen oppositionelle Fernsehsender verh\u00e4ngt. S\u00f6zc\u00fc TV wurde mit einem zehnt\u00e4gigen Sendeverbot belegt, w\u00e4hrend Halk TV und TELE1 mit Geldstrafen belegt wurden. Sendeverbot f\u00fcr S\u00f6zc\u00fc TV Grundlage f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T05:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E.Karaduman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"E.Karaduman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/\"},\"author\":{\"name\":\"E.Karaduman\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/b46c79ad45fc36dbd29149cc1e46f1a8\"},\"headline\":\"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1\",\"datePublished\":\"2025-05-30T05:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0972.jpeg\",\"articleSection\":[\"Nachrichten\",\"Schlagzeile\",\"Verletzungen der Medienrechte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/\",\"name\":\"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0972.jpeg\",\"datePublished\":\"2025-05-30T05:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0972.jpeg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0972.jpeg\",\"width\":1500,\"height\":1040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/b46c79ad45fc36dbd29149cc1e46f1a8\",\"name\":\"E.Karaduman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g\",\"caption\":\"E.Karaduman\"},\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/y-aydin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/","og_locale":"de_DE","og_type":"article","og_title":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists","og_description":"Der Druck auf kritische Medien in der T\u00fcrkei nimmt weiter zu. Die Rundfunk- und Fernsehaufsichtsbeh\u00f6rde (RT\u00dcK) setzt ihre Linie der Zensur und Repression fort und hat erneut Ma\u00dfnahmen gegen oppositionelle Fernsehsender verh\u00e4ngt. S\u00f6zc\u00fc TV wurde mit einem zehnt\u00e4gigen Sendeverbot belegt, w\u00e4hrend Halk TV und TELE1 mit Geldstrafen belegt wurden. Sendeverbot f\u00fcr S\u00f6zc\u00fc TV Grundlage f\u00fcr [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2025-05-30T05:24:31+00:00","og_image":[{"width":1500,"height":1040,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg","type":"image\/jpeg"}],"author":"E.Karaduman","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"E.Karaduman","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/"},"author":{"name":"E.Karaduman","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/b46c79ad45fc36dbd29149cc1e46f1a8"},"headline":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1","datePublished":"2025-05-30T05:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/"},"wordCount":444,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg","articleSection":["Nachrichten","Schlagzeile","Verletzungen der Medienrechte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/","url":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/","name":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1 - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg","datePublished":"2025-05-30T05:24:31+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/05\/IMG_0972.jpeg","width":1500,"height":1040},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/zensur-und-strafen-gegen-regierungskritische-sender-in-der-tuerkei-sendeverbot-fuer-soezcue-tv-geldbussen-fuer-halk-tv-und-tele1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Zensur und Strafen gegen regierungskritische Sender in der T\u00fcrkei: Sendeverbot f\u00fcr S\u00f6zc\u00fc TV, Geldbu\u00dfen f\u00fcr Halk TV und TELE1"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/b46c79ad45fc36dbd29149cc1e46f1a8","name":"E.Karaduman","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/087e2ebf9142b46130cad61cbfe237a0dfd38d149b528559b06ada307fb17f02?s=96&d=mm&r=g","caption":"E.Karaduman"},"url":"https:\/\/internationaljournalists.org\/de\/author\/y-aydin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/40149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=40149"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/40149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/40150"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=40149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=40149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=40149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}