{"id":36161,"date":"2024-03-08T10:44:06","date_gmt":"2024-03-08T09:44:06","guid":{"rendered":"https:\/\/ijaev.org\/?p=36161"},"modified":"2024-03-08T12:18:41","modified_gmt":"2024-03-08T11:18:41","slug":"ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/","title":{"rendered":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden"},"content":{"rendered":"<p>Anl\u00e4sslich des Internationalen Frauentags 2024 erkl\u00e4rt sich die Internationale Journalistenvereinigung (IJA) solidarisch mit Journalistinnen und Medienschaffenden auf der ganzen Welt, w\u00fcrdigt ihren unausl\u00f6schlichen Beitrag zum Journalismus und bekr\u00e4ftigt unser Engagement f\u00fcr ihre Sicherheit. Der Mut und die Widerstandsf\u00e4higkeit von Journalistinnen, die oft von der Frontlinie eines Konflikts berichten, die sich nicht scheuen, die Wahrheit \u00fcber Machtinhaber und unerz\u00e4hlte Geschiechtenans Licht bringen, sind das R\u00fcckgrat einer freien und unabh\u00e4ngigen Presse.<\/p>\n<p>Der Weg zur Gleichberechtigung ist jedoch mit vielen Herausforderungen verbunden. Journalistinnen sind besonderen Risiken ausgesetzt, die ihre freie Arbeit behindern &#8211; von geschlechtsspezifischer Gewalt und Bel\u00e4stigung bis hin zu systematischer Diskriminierung innerhalb der Medienbranche. Diese Bedrohungen stellen nicht nur eine Verletzung der individuellen Rechte dar, sondern sind auch ein direkter Angriff auf die Vielfalt und Freiheit der Presse. Wenn die Stimmen von Journalistinnen zum Schweigen gebracht werden, werden der Welt kritische Perspektiven vorenthalten.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-36159 aligncenter\" src=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-300x200.jpg\" alt=\"\" width=\"378\" height=\"252\" srcset=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-300x200.jpg 300w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-1024x683.jpg 1024w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-768x512.jpg 768w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-1536x1025.jpg 1536w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-750x500.jpg 750w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia-1140x760.jpg 1140w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20200421__1QQ7D4__v4__Preview__ElSalvadorHealthVirusMedia.jpg 1799w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/><\/p>\n<p>Die Sicherheit von Journalistinnen und Medienschaffenden ist von gr\u00f6\u00dfter Bedeutung. Es reicht nicht aus, die Gefahren, denen sie ausgesetzt sind, anzuerkennen; wir m\u00fcssen aktiv daran arbeiten, ein Umfeld zu schaffen, in dem sie ihre Aufgaben ohne Angst vor Repressalien oder Schaden erf\u00fcllen k\u00f6nnen. Dazu geh\u00f6rt die Einf\u00fchrung strenger Sicherheitsprotokolle, die Bereitstellung rechtlicher und psychologischer Unterst\u00fctzung und die F\u00f6rderung einer Arbeitsplatzkultur, die Gleichheit und Respekt f\u00f6rdert. Medienorganisationen und Regierungen m\u00fcssen f\u00fcr den Schutz der Rechte von Journalistinnen zur Rechenschaft gezogen werden und daf\u00fcr sorgen, dass T\u00e4ter, die Gewalt und Bel\u00e4stigung aus\u00fcben, vor Gericht gestellt werden.<\/p>\n<p>Die Bedeutung von Frauen im Journalismus kann gar nicht hoch genug eingesch\u00e4tzt werden. Sie bringen unterschiedliche Sichtweisen ein, stellen Stereotypen in Frage und bereichern die Berichterstattung mit Geschichten, die andernfalls vielleicht unbemerkt bleiben w\u00fcrden. Ihre Pr\u00e4senz in den Redaktionen und vor Ort sorgt f\u00fcr eine umfassendere Darstellung globaler Ereignisse und tr\u00e4gt zu einer gut informierten \u00d6ffentlichkeit bei. Durch die F\u00f6rderung von Journalistinnen setzen wir uns nicht nur f\u00fcr die Gleichstellung der Geschlechter ein, sondern auch f\u00fcr die St\u00e4rke und Integrit\u00e4t des Journalismus insgesamt.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-36156 aligncenter lazyload\" data-src=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-300x200.jpg\" alt=\"\" width=\"377\" height=\"251\" data-srcset=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-300x200.jpg 300w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-1024x683.jpg 1024w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-768x512.jpg 768w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-1536x1024.jpg 1536w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-750x500.jpg 750w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict-1140x760.jpg 1140w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/AFP__20220424__328V82T__v4__Preview__TopshotUkraineRussiaConflict.jpg 1800w\" data-sizes=\"(max-width: 377px) 100vw, 377px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 377px; --smush-placeholder-aspect-ratio: 377\/251;\" \/><\/p>\n<p>An diesem Internationalen Frauentag bekr\u00e4ftigt die IJA ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung der Rolle von Journalistinnen und Medienschaffenden. Wir als IJA setzen daher einen besonderen Fokus auf junge Journalistinnen in unserer Nachwuchsf\u00f6rderung und m\u00f6chten damit einen nachhaltigen Beitrag f\u00fcr St\u00e4rkung der Journalistinnen und Medienschaffenden in der europ\u00e4ischen Medienlandschaft leisten.<\/p>\n<p>Wir rufen Medienorganisationen, politische Entscheidungstr\u00e4ger und die internationale Gemeinschaft auf, sich uns bei dieser wichtigen Aufgabe anzuschlie\u00dfen. Gemeinsam k\u00f6nnen wir die Herausforderungen bek\u00e4mpfen, mit denen Frauen im Journalismus konfrontiert sind, und den Weg f\u00fcr eine gerechtere, sichere und lebendige Medienlandschaft ebnen.<\/p>\n<p>Lassen Sie uns die Errungenschaften von Journalistinnen anerkennen und uns dazu verpflichten, ihre Rechte zu sch\u00fctzen und sicherzustellen, dass ihre Stimmen laut und deutlich geh\u00f6rt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich des Internationalen Frauentags 2024 erkl\u00e4rt sich die Internationale Journalistenvereinigung (IJA) solidarisch mit Journalistinnen und Medienschaffenden auf der ganzen Welt, w\u00fcrdigt ihren unausl\u00f6schlichen Beitrag zum Journalismus und bekr\u00e4ftigt unser Engagement f\u00fcr ihre Sicherheit. Der Mut und die Widerstandsf\u00e4higkeit von Journalistinnen, die oft von der Frontlinie eines Konflikts berichten, die sich nicht scheuen, die Wahrheit \u00fcber [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":36153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"2","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[8323,2868],"tags":[],"class_list":["post-36161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten-de","category-schlagzeile"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Anl\u00e4sslich des Internationalen Frauentags 2024 erkl\u00e4rt sich die Internationale Journalistenvereinigung (IJA) solidarisch mit Journalistinnen und Medienschaffenden auf der ganzen Welt, w\u00fcrdigt ihren unausl\u00f6schlichen Beitrag zum Journalismus und bekr\u00e4ftigt unser Engagement f\u00fcr ihre Sicherheit. Der Mut und die Widerstandsf\u00e4higkeit von Journalistinnen, die oft von der Frontlinie eines Konflikts berichten, die sich nicht scheuen, die Wahrheit \u00fcber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T09:44:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T11:18:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden\",\"datePublished\":\"2024-03-08T09:44:06+00:00\",\"dateModified\":\"2024-03-08T11:18:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/\"},\"wordCount\":506,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg\",\"articleSection\":[\"Nachrichten\",\"Schlagzeile\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/\",\"name\":\"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg\",\"datePublished\":\"2024-03-08T09:44:06+00:00\",\"dateModified\":\"2024-03-08T11:18:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/","og_locale":"de_DE","og_type":"article","og_title":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists","og_description":"Anl\u00e4sslich des Internationalen Frauentags 2024 erkl\u00e4rt sich die Internationale Journalistenvereinigung (IJA) solidarisch mit Journalistinnen und Medienschaffenden auf der ganzen Welt, w\u00fcrdigt ihren unausl\u00f6schlichen Beitrag zum Journalismus und bekr\u00e4ftigt unser Engagement f\u00fcr ihre Sicherheit. Der Mut und die Widerstandsf\u00e4higkeit von Journalistinnen, die oft von der Frontlinie eines Konflikts berichten, die sich nicht scheuen, die Wahrheit \u00fcber [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2024-03-08T09:44:06+00:00","article_modified_time":"2024-03-08T11:18:41+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden","datePublished":"2024-03-08T09:44:06+00:00","dateModified":"2024-03-08T11:18:41+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/"},"wordCount":506,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg","articleSection":["Nachrichten","Schlagzeile"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/","url":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/","name":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg","datePublished":"2024-03-08T09:44:06+00:00","dateModified":"2024-03-08T11:18:41+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-08-at-09.28.27.jpeg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/ija-bekraeftigt-ihr-engagement-fuer-die-sicherheit-und-die-staerkung-von-journalistinnen-und-weiblichen-medienschaffenden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"IJA bekr\u00e4ftigt ihr Engagement f\u00fcr die Sicherheit und die St\u00e4rkung von Journalistinnen und weiblichen Medienschaffenden"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/36161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=36161"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/36161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/36153"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=36161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=36161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=36161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}