{"id":32490,"date":"2023-05-16T15:54:28","date_gmt":"2023-05-16T13:54:28","guid":{"rendered":"https:\/\/ijaev.org\/?p=32490"},"modified":"2023-05-16T16:09:43","modified_gmt":"2023-05-16T14:09:43","slug":"meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/","title":{"rendered":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger"},"content":{"rendered":"<p>Twitter hat die vor den Wahlen in der T\u00fcrkei gesperrten Accounts und Postings geteilt. Dies sei notwendig um eine vollst\u00e4ndige Sperre zu vermeiden, so Musk. Doch als gesellschaftliches Recht darf man mit der Informationsfreiheit so nicht verhandeln. Das sollte auch Musk klar sein.<\/p>\n<p>Die Informationsfreiheit ist ein gesellschaftliches Recht, dass durch die \u00f6ffentliche Meinung eine Kontrolle der Politik gew\u00e4hrleistet. Doch in letzter Zeit hat sich diese Formation verkehrt und das Medium ist zu einem durch die politische Willk\u00fcr kontrollierten Apparat verkommen.<\/p>\n<p>Die j\u00fcngsten Ereignisse in der T\u00fcrkei haben gezeigt, wie anf\u00e4llig Twitter gegen\u00fcber den Willen der Regierungen sein kann. Schon bei den Erdbeben vor 3 Monaten, kam es dazu, dass Twitter in der T\u00fcrkei f\u00fcr mehrere Stunden vollst\u00e4ndig gesperrt wurde. Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.<\/p>\n<p>Deshalb ger\u00e4t Twitter und somit Elon Musk in Kritik wegen Umgang mit Meinungsfreiheit in der T\u00fcrkei. Trotz drohender Drosselung hatte das Unternehmen Ma\u00dfnahmen gegen 4 Konten und 409 Tweets ergriffen, um den Dienst w\u00e4hrend des Wahlwochenendes aufrechtzuerhalten. Bedenken zur Einschr\u00e4nkung der Meinungsfreiheit wurden ge\u00e4u\u00dfert, aber Twitter hat bisher nur gegen 4 von 5 Gerichtsbeschl\u00fcssen Einspruch eingelegt. Die Frage nach dem Engagement f\u00fcr Meinungsfreiheit bleibt bestehen.<\/p>\n<p>Unter den Gesperrten sind viele Journalist*innen, Nachrichten-Websites und Namen wie Cevheri G\u00fcven, Hakan \u015e\u00fck\u00fcr und Ak\u0131n \u0130pek.<\/p>\n<p>Jetzt hat <a href=\"https:\/\/twitter.com\/GlobalAffairs\">Twitter<\/a>\u00a0eine bemerkenswerte Erkl\u00e4rung dazu abgegeben:<\/p>\n<blockquote><p>Wir haben die ganze letzte Woche \u00fcber mit der t\u00fcrkischen Regierung verhandelt, die uns klar gemacht hat, dass Twitter der einzige soziale Mediendienst ist, der sich nicht vollst\u00e4ndig an die bestehenden Gerichtsbeschl\u00fcsse h\u00e4lt.<\/p>\n<p>Wir erhielten &#8211; nach mehreren derartigen Warnungen &#8211; eine unserer Meinung nach endg\u00fcltige Drohung, den Dienst zu drosseln. Um Twitter \u00fcber das Wahlwochenende verf\u00fcgbar zu halten, ergriffen wir Ma\u00dfnahmen gegen vier Konten und 409 Tweets, die per Gerichtsbeschluss identifiziert worden waren.<\/p>\n<p>Wir haben unsere Bedenken bez\u00fcglich der Meinungsfreiheit direkt mitgeteilt. Wir werden weiterhin vor Gericht Einspruch erheben, wie wir es bei allen Antr\u00e4gen getan haben, aber vor Beginn der Wahl waren keine weiteren rechtlichen Schritte m\u00f6glich.<\/p>\n<p>Gegen Twitter wurden f\u00fcnf Gerichtsbeschl\u00fcsse zu diesen Ma\u00dfnahmen erlassen, gegen vier davon haben wir bereits Einspruch eingelegt. W\u00e4hrend einer unserer Einspr\u00fcche abgelehnt wurde, werden drei davon noch gepr\u00fcft. Gegen die f\u00fcnfte Anordnung werden wir morgen Einspruch einlegen.&#8220;<\/p><\/blockquote>\n<p>Mit Presse- und Meinungsfreiheit sollte nicht verhandelt werden.Wir fordern Twitter dazu auf, die sofortige Aufhebung dieser Sperren zu vollziehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.<\/p>\n","protected":false},"author":17,"featured_media":32483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"0","show_post_author":"0","show_post_author_image":"1","show_post_date":"0","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"2","show_author_box":"0","show_post_related":"1","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[2868,4680],"tags":[5321,4721,3060,8024],"class_list":["post-32490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlagzeile","category-up-manset","tag-erdogan-3","tag-pressefreiheit-2","tag-tuerkei-de","tag-twitter-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists<\/title>\n<meta name=\"description\" content=\"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T13:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-16T14:09:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger\",\"datePublished\":\"2023-05-16T13:54:28+00:00\",\"dateModified\":\"2023-05-16T14:09:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/\"},\"wordCount\":443,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg\",\"keywords\":[\"Erdo\u011fan\",\"Pressefreiheit\",\"t\u00fcrkei\",\"Twitter\"],\"articleSection\":[\"Schlagzeile\",\"up-manset\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/\",\"name\":\"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg\",\"datePublished\":\"2023-05-16T13:54:28+00:00\",\"dateModified\":\"2023-05-16T14:09:43+00:00\",\"description\":\"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg\",\"width\":720,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists","description":"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/","og_locale":"de_DE","og_type":"article","og_title":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists","og_description":"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.","og_url":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2023-05-16T13:54:28+00:00","article_modified_time":"2023-05-16T14:09:43+00:00","og_image":[{"width":720,"height":400,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger","datePublished":"2023-05-16T13:54:28+00:00","dateModified":"2023-05-16T14:09:43+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/"},"wordCount":443,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg","keywords":["Erdo\u011fan","Pressefreiheit","t\u00fcrkei","Twitter"],"articleSection":["Schlagzeile","up-manset"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/","url":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/","name":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg","datePublished":"2023-05-16T13:54:28+00:00","dateModified":"2023-05-16T14:09:43+00:00","description":"Nun kommt es 2 Tage vor den Wahlen in der T\u00fcrkei, zu einer gezielten Inhaltssperre von wichtigen Konten und Postings.","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2023\/05\/erdogan-elon-musk-ile-gorusebilecegini-soyledi-1083531-5.jpg","width":720,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/meinungsfreiheit-unter-musk-wird-immer-fragwuerdiger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Twitter und T\u00fcrkei-Wahl: Meinungsfreiheit unter Musk wird immer fragw\u00fcrdiger"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/32490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=32490"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/32490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/32483"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=32490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=32490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=32490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}