{"id":30321,"date":"2022-12-21T13:24:36","date_gmt":"2022-12-21T12:24:36","guid":{"rendered":"https:\/\/ijaev.org\/?p=30321"},"modified":"2022-12-21T13:24:40","modified_gmt":"2022-12-21T12:24:40","slug":"schweden-lehnt-auslieferung-von-buelent-kenes-ab","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/","title":{"rendered":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BEDINGUNG DER DOPPELTEN SCHULD NICHT ERF\u00dcLLT<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;Es ist klar, dass es in diesem Fall verschiedene Hindernisse f\u00fcr die Auslieferung gibt&#8220;, sagte der Richter des Obersten Gerichtshofs Petter Asp in einer Presseerkl\u00e4rung und f\u00fcgte hinzu, dass die Bedingung der doppelten Schuld in Bezug auf eine der Anklagen nicht erf\u00fcllt sei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schweden, das nach dem Einmarsch Russlands in der Ukraine zusammen mit Finnland einen Antrag auf NATO-Mitgliedschaft gestellt hat, wartet auf die Zustimmung Ankaras. Ankara erkl\u00e4rt, dass Finnland und Schweden ihren Auslieferungsantr\u00e4gen so schnell wie m\u00f6glich nachkommen m\u00fcssen, um f\u00fcr eine NATO-Mitgliedschaft zugelassen zu werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anl\u00e4sslich des Besuchs des schwedischen Ministerpr\u00e4sidenten Ulf Kristersson in Ankara forderte AKP-Pr\u00e4sident Recep Tayyip Erdo\u011fan die Auslieferung des Journalisten B\u00fclent Kene\u015f.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"702\" height=\"445\" src=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/bulent-kenes-13.jpg\" alt=\"\" class=\"wp-image-30309\" srcset=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/bulent-kenes-13.jpg 702w, https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/bulent-kenes-13-300x190.jpg 300w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.<\/p>\n","protected":false},"author":17,"featured_media":30322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"0","show_post_author":"0","show_post_author_image":"1","show_post_date":"0","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"2","show_author_box":"0","show_post_related":"1","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[2868,4680],"tags":[5587,6659,7271,3060],"class_list":["post-30321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlagzeile","category-up-manset","tag-erdogan-4","tag-ija-5","tag-schweden","tag-tuerkei-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists<\/title>\n<meta name=\"description\" content=\"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T12:24:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T12:24:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Schweden lehnt Auslieferung von B\u00fclent Kenes ab\",\"datePublished\":\"2022-12-21T12:24:36+00:00\",\"dateModified\":\"2022-12-21T12:24:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/kenes1-scaled.jpg\",\"keywords\":[\"erdogan\",\"ija\",\"Schweden\",\"t\u00fcrkei\"],\"articleSection\":[\"Schlagzeile\",\"up-manset\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/\",\"name\":\"Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/kenes1-scaled.jpg\",\"datePublished\":\"2022-12-21T12:24:36+00:00\",\"dateModified\":\"2022-12-21T12:24:40+00:00\",\"description\":\"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/kenes1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/kenes1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Bulent Kenes, a 53 year old Turkish journalist who fled from his country to Sweden due to his critics of the Turkish President, poses for a photo on November 10, 2022 near Stockholm. - The Turkish president Recep Tayyip Erdogan said on November 8, 2022 he wanted the Turkish journalist deported to Turkey as a part of Sweden's bid to join Nato. (Photo by Jonathan NACKSTRAND \\\/ AFP)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schweden lehnt Auslieferung von B\u00fclent Kenes ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists","description":"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/","og_locale":"de_DE","og_type":"article","og_title":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists","og_description":"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.","og_url":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2022-12-21T12:24:36+00:00","article_modified_time":"2022-12-21T12:24:40+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab","datePublished":"2022-12-21T12:24:36+00:00","dateModified":"2022-12-21T12:24:40+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/"},"wordCount":179,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg","keywords":["erdogan","ija","Schweden","t\u00fcrkei"],"articleSection":["Schlagzeile","up-manset"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/","url":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/","name":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg","datePublished":"2022-12-21T12:24:36+00:00","dateModified":"2022-12-21T12:24:40+00:00","description":"Das oberste schwedische Gericht hat die Auslieferung des Journalisten B\u00fclent Kene\u015f abgelehnt. Erdogan geht aber nicht mit leeren H\u00e4nden aus. Kurdische Exilant*innen werden weiterhin an die T\u00fcrkei ausgeliefert. Die Gleichgewichtspolitik von Schweden sollte demnach weiterhin kritisch betrachtet werden.","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/12\/kenes1-scaled.jpg","width":2560,"height":1707,"caption":"Bulent Kenes, a 53 year old Turkish journalist who fled from his country to Sweden due to his critics of the Turkish President, poses for a photo on November 10, 2022 near Stockholm. - The Turkish president Recep Tayyip Erdogan said on November 8, 2022 he wanted the Turkish journalist deported to Turkey as a part of Sweden's bid to join Nato. (Photo by Jonathan NACKSTRAND \/ AFP)"},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/schweden-lehnt-auslieferung-von-buelent-kenes-ab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Schweden lehnt Auslieferung von B\u00fclent Kenes ab"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/30321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=30321"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/30321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/30322"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=30321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=30321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=30321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}