{"id":27530,"date":"2022-09-28T12:58:20","date_gmt":"2022-09-28T10:58:20","guid":{"rendered":"https:\/\/ijaev.org\/?p=27530"},"modified":"2022-09-28T12:58:24","modified_gmt":"2022-09-28T10:58:24","slug":"fotojournalist-innen-im-fadenkreuz","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/","title":{"rendered":"Fotojournalist: innen im Fadenkreuz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Fotojournalist Wagner Ribeiro bei der Berichterstattung \u00fcber antifaschistische Proteste in S\u00e3o Paulo am 7.September 2017 (Brasiliens Unabh\u00e4ngigkeitstag). Foto: Rodrigo Pivas Der Beruf des Fotojournalisten in Brasilien ist ein Metier f\u00fcr leidenschaftliche Geschichtenerz\u00e4hler. Diese Feststellung gilt insbesondere f\u00fcr Profis, die \u00fcber Proteste und Konflikte berichten. Die Arbeitsausr\u00fcstung ist extrem \u00fcberteuert, die Risiken des Jobs sind gro\u00df und die Bezahlung ist absurd niedrig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Arbeit ist in den letzten f\u00fcnf Jahren aus zwei Gr\u00fcnden komplexer geworden. Erstens ist die Zahl der Menschen, die Fotos machen, stark gestiegen. Zweitens wurden im Zuge des Wahlkampfs und der Ernennung von Jair Bolsonaro zum neuen Pr\u00e4sidenten des Landes Fotojournalisten von der Polizei und von B\u00fcrgern, die ihn unterst\u00fctzen, angegriffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>WER IST AUF DER STRASSE, UM PROTESTE<\/strong><strong> ZU FOTOGRAFIEREN?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es bei Protesten zu Spannungen kommt, sind Fotojournalist:innen von kleinen, mittleren und gro\u00dfen Zeitungen, Zeitschriften und Internetportalen vor Ort. Das bedeutet, dass die angeheuerten Profis sich weitgehend auf die wirtschaftliche und rechtliche Unterst\u00fctzung von Redaktionen und ihren Zuarbeiter:innen verlassen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die gr\u00f6\u00dfte Gruppe sind die unabh\u00e4ngigen Fotojournalist:innen. Diese Profis stehen vor der Herausforderung, ihre Arbeit ohne das Siegel eines Nachrichtenunternehmens, ohne finanzielle oder rechtliche Unterst\u00fctzung erledigen zu m\u00fcssen. Noch in der Hitze des Gefechts versuchen sie, die Fotos f\u00fcr Bildnachrichten zu verkaufen, und erhalten im Durchschnitt 15 R$ (etwa 3 US$) pro Foto. Wenn sie sie \u00fcberhaupt verkaufen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DAS<\/strong><strong> <\/strong><strong>PARADOXON<\/strong><strong> <\/strong><strong>DER<\/strong><strong> <\/strong><strong>PRESSEIDENTIFIKATION<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Polizei und die B\u00fcrger der rebellischen Rechten sowie die Anh\u00e4nger des Pr\u00e4sidenten kennen die Gesichter der Fotojournalist:innen. Mit anderen Worten, sie wissen, wohin sie ihre Waffen, F\u00e4uste und verbalen Angriffe richten m\u00fcssen. Wenn sie sich als Fotojournalist zu erkennen geben, bringen sie sich m\u00f6glicherweise in eine noch gef\u00e4hrlichere Situation. Wenn die einzige M\u00f6glichkeit darin besteht, unbemerkt zu arbeiten, machen sich viele Fachleute nicht einmal die M\u00fche, eine Sicherheitsausr\u00fcstung zu tragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies ist ein Paradoxon des Berufs in Brasilien und vielleicht weltweit. Einerseits ist die Schutzausr\u00fcstung unerl\u00e4sslich, um die k\u00f6rperliche Unversehrtheit der Fachleute zu bewahren. Dennoch kann das Wort \u201ePresse\u201c auf Helmen und Sicherheitswesten eine Zielscheibe auf dem Kopf oder auf dem R\u00fccken von Fotojournalist:innen sein. Vor diesem Hintergrund haben die Fotojournalist:innen neue Mittel f\u00fcr ihre Arbeit entwickelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Statt Helme und Westen mit dem Aufdruck \u201ePresse\u201c zu verwenden, haben sich die Fotojournalist:innen f\u00fcr abnehmbare Klettverschl\u00fcsse entschieden, die bei Bedarf leicht entfernt werden k\u00f6nnen. Kurioserweise wurde diese Idee von einer Strategie abgekupfert, die von der brasilianischen Polizei angewendet wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obwohl es illegal ist, entfernen einige Polizeibeamte bei Protesten ihre Abzeichen von ihren Uniformen, um zu verhindern, dass Angreifer leicht identifiziert werden k\u00f6nnen. Dies h\u00e4lt Fotojournalist:innen davon ab, den Missbrauch von Gewalt und sogar physische Gewalt gegen Fotojournalist:innen zu dokumentieren, was dazu f\u00fchrt, dass noch weniger F\u00e4lle in die Berichterstattung aufgenommen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ZU WENIG BERICHTERSTATTUNG \u00dcBER F\u00c4LLE VON GEWALT<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe bei der Journalistengewerkschaft Arfoc (Brasilianischer Verband der Foto- und Filmreporter) und Abraji (Brasilianischer Verband f\u00fcr investigativen Journalismus) nach Daten \u00fcber Gewalt gegen Fotojournalist:innen gesucht. Nur Abraji hat einige Informationen zur Verf\u00fcgung gestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Angaben von Abraji gab es im Jahr 2021 in Brasilien 22 F\u00e4lle von Aggression gegen Fotojournalist:innen und Kameraleute. Es gibt einen Grund daf\u00fcr, dass die Daten \u00fcber Angriffe auf Fotojournalist:innen und Kameraleute nur f\u00fcr dieses Jahr verf\u00fcgbar sind. Nach Angaben von Katia Brembatti, der Direktorin der Einrichtung, wurden Fotojournalist:innen in den Vorjahren zusammen mit anderen Medienschaffenden gez\u00e4hlt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Analyse der von Abraji gemeldeten F\u00e4lle,die sich auf die Arbeit des Verfassers dieses Artikels vor Ort st\u00fctzt, kann man eine Reihe von Gewalttaten gegen Fotojournalist:innen feststellen, die nicht in der Shortlist der Institutionen enthalten sind. Abgesehen davon, dass die Journalistengewerkschaft und Arfoc keine genauen Daten liefern, ist die Tatsache, dass \u00fcber Gewalt gegen Fotojournalist:innen und Kameraleute in Brasilien zu wenig berichtet wird, sehr beunruhigend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DIE<\/strong><strong> <\/strong><strong>FOTOJOURNALIST:INNEN<\/strong><strong> <\/strong><strong>SIND DIE<\/strong><strong> <\/strong><strong>ERZ\u00c4HLER DER FAKTEN<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Brasilien sind Fotojournalist:innen und Kamera leute in den Print- und Digitalmedien die Berufsgruppen, die am ehesten von Gewalt betroffen sind, wenn sie \u00fcber Proteste und Konflikte berichten, da sie sich an vorderster Front befinden. Die Fotojournalist:innen \u00fcbermitteln die Informationen vom Schauplatz an die Text-Berichterstatter:innen, die in den Redaktionen die Geschichten schreiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Fotojournalist ist somit der Erz\u00e4hler der geschriebenen Fakten. Daher m\u00fcssen Medien, \u00f6ffentliche Organisationen und Unternehmen des Sektors nach Mechanismen suchen, um die Sicherheit von Fotojournalist:innen und Kameraleuten zu gew\u00e4hrleisten. Dies ist eines der dringenden Probleme, denen wir uns in Brasilien und weltweit stellen m\u00fcssen. Die Leidenschaft der Fotojournalist:innen reicht nicht aus, um gute Geschichten zu erz\u00e4hlen. Sie brauchen auch Schutz und menschenw\u00fcrdige Arbeitsbedingungen.<img decoding=\"async\" width=\"7\" height=\"7\" src=\"\">Wagner Ribeiro ist ein brasilianischer Professor und Fotojournalist. Er hat f\u00fcr verschiedene Zeitungen, Zeitschriften und das Fernsehen gearbeitet und \u00fcber Proteste, Konflikte und humanit\u00e4re Krisen in Lateinamerika, Europa und dem Nahen Osten berichtet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fotojournalist Wagner Ribeiro bei der Berichterstattung \u00fcber antifaschistische Proteste in S\u00e3o Paulo am 7.September 2017 (Brasiliens Unabh\u00e4ngigkeitstag). Foto: Rodrigo Pivas Der Beruf des Fotojournalisten in Brasilien ist ein Metier f\u00fcr leidenschaftliche Geschichtenerz\u00e4hler. Diese Feststellung gilt insbesondere f\u00fcr Profis, die \u00fcber Proteste und Konflikte berichten. Die Arbeitsausr\u00fcstung ist extrem \u00fcberteuert, die Risiken des Jobs sind [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":27162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"0","show_post_author":"0","show_post_author_image":"1","show_post_date":"0","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"2","show_author_box":"0","show_post_related":"1","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676],"tags":[7127,4694,4721,7126],"class_list":["post-27530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","tag-fotojournalist","tag-international-journalists-association","tag-pressefreiheit-2","tag-wagner-ribeiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fotojournalist: innen im Fadenkreuz - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotojournalist: innen im Fadenkreuz - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Der Fotojournalist Wagner Ribeiro bei der Berichterstattung \u00fcber antifaschistische Proteste in S\u00e3o Paulo am 7.September 2017 (Brasiliens Unabh\u00e4ngigkeitstag). Foto: Rodrigo Pivas Der Beruf des Fotojournalisten in Brasilien ist ein Metier f\u00fcr leidenschaftliche Geschichtenerz\u00e4hler. Diese Feststellung gilt insbesondere f\u00fcr Profis, die \u00fcber Proteste und Konflikte berichten. Die Arbeitsausr\u00fcstung ist extrem \u00fcberteuert, die Risiken des Jobs sind [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T10:58:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T10:58:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Fotojournalist: innen im Fadenkreuz\",\"datePublished\":\"2022-09-28T10:58:20+00:00\",\"dateModified\":\"2022-09-28T10:58:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/\"},\"wordCount\":850,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WAGNER-RIBEIRO.png\",\"keywords\":[\"fotojournalist\",\"International Journalists Association\",\"Pressefreiheit\",\"WAGNER RIBEIRO\"],\"articleSection\":[\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/\",\"name\":\"Fotojournalist: innen im Fadenkreuz - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WAGNER-RIBEIRO.png\",\"datePublished\":\"2022-09-28T10:58:20+00:00\",\"dateModified\":\"2022-09-28T10:58:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WAGNER-RIBEIRO.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WAGNER-RIBEIRO.png\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/fotojournalist-innen-im-fadenkreuz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotojournalist: innen im Fadenkreuz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotojournalist: innen im Fadenkreuz - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/","og_locale":"de_DE","og_type":"article","og_title":"Fotojournalist: innen im Fadenkreuz - International Journalists","og_description":"Der Fotojournalist Wagner Ribeiro bei der Berichterstattung \u00fcber antifaschistische Proteste in S\u00e3o Paulo am 7.September 2017 (Brasiliens Unabh\u00e4ngigkeitstag). Foto: Rodrigo Pivas Der Beruf des Fotojournalisten in Brasilien ist ein Metier f\u00fcr leidenschaftliche Geschichtenerz\u00e4hler. Diese Feststellung gilt insbesondere f\u00fcr Profis, die \u00fcber Proteste und Konflikte berichten. Die Arbeitsausr\u00fcstung ist extrem \u00fcberteuert, die Risiken des Jobs sind [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2022-09-28T10:58:20+00:00","article_modified_time":"2022-09-28T10:58:24+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Fotojournalist: innen im Fadenkreuz","datePublished":"2022-09-28T10:58:20+00:00","dateModified":"2022-09-28T10:58:24+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/"},"wordCount":850,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png","keywords":["fotojournalist","International Journalists Association","Pressefreiheit","WAGNER RIBEIRO"],"articleSection":["Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/","url":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/","name":"Fotojournalist: innen im Fadenkreuz - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png","datePublished":"2022-09-28T10:58:20+00:00","dateModified":"2022-09-28T10:58:24+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/09\/WAGNER-RIBEIRO.png","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/fotojournalist-innen-im-fadenkreuz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Fotojournalist: innen im Fadenkreuz"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/27530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=27530"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/27530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/27162"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=27530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=27530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=27530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}