{"id":25789,"date":"2022-05-03T08:01:00","date_gmt":"2022-05-03T06:01:00","guid":{"rendered":"https:\/\/ijaev.org\/?p=25789"},"modified":"2022-04-30T15:21:29","modified_gmt":"2022-04-30T13:21:29","slug":"die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/","title":{"rendered":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der gemeinsame Punkt der Erkl\u00e4rungen, die von den Berufsverb\u00e4nden der Weltpresse am 3. Mai, dem Welttag der Pressefreiheit, ver\u00f6ffentlicht werden, ist stets die Forderung nach einem ,,Ende der Gewalt und Zensur gegen JournalistInnen&#8220;. Da dieser Aufforderung jedoch nicht ausreichend nachgekommen wird, werden zwei unverzichtbare Bestandteile von Demokratien, ,,die Meinungs- und Gedankenfreiheit und das Recht auf Zugang zu \u00f6ffentlichen Informationen&#8220;, verletzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Lebenselixier demokratischer Staaten h\u00e4ngt von der Freiheit der Medien ab. JournalistInnen, die unbedingten Verfechter der Meinungsfreiheit, sorgen daf\u00fcr, dass der Staat gegen\u00fcber der \u00d6ffentlichkeit rechenschaftspflichtig ist. PressevertreterInnen recherchieren, schreiben und legen im Namen der \u00d6ffentlichkeit Rechenschaft ab. Sie sind die Sprecher des Volkes, nicht der Machthaber. Diejenigen, die manipulieren, sind diejenigen, die die \u00d6ffentlichkeit unbegr\u00fcndet informieren, ohne die Fakten zu pr\u00fcfen, entgegen ihrer Berufsgrunds\u00e4tze. Solche Manipulationen erleichtern die Korruption von Regimen. Es sollte nicht vergessen werden, dass die Meinungsfreiheit der Eckpfeiler von Demokratien ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In unserer Welt, in der unterdr\u00fcckerische Regime auf dem Vormarsch sind, ist die Bedeutung von JournalistInnen, die ihre Arbeit richtig machen, noch gr\u00f6\u00dfer geworden. Denn solche Regime erhalten ihr Machtstreben aufrecht, indem sie einen eisernen Vorhang zwischen den B\u00fcrgerInnen und der Realit\u00e4t ziehen. Zu diesem Zweck wenden sie ihr repressives Regime auf JournalistInnen an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einerseits gibt es in der Ukraine einen traditionellen Krieg mit Panzern und Raketen. Auf der anderen Seite gibt es den sogenannten ,,hybriden&#8220; Desinformationskrieg, den Russland schon vor Monaten begonnen hat. Wir glauben, dass sich der Verlauf dieses Krieges dank der Fakten, die von JournalistInnen, die ihre Arbeit unter schwierigsten Bedingungen im Kriegsgebiet fortsetzen, ver\u00f6ffentlicht werden, \u00e4ndern wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ohne die JournalistInnen, die sich nicht beugen und ihre Feder nicht verkaufen, h\u00e4tten wir vielleicht nie von der Korruption der Macht und den Tr\u00e4nen erfahren, die in den von autorit\u00e4ren Regimen beherrschten L\u00e4ndern vergossen werden. Doch die mutigen und ehrenhaften JournalistInnen haben trotz der Einsch\u00fcchterung durch die Regime nie ihre Haltung aufgegeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr denn je brauchen wir engagierte JournalistInnen. Wir m\u00fcssen ihnen unsere volle Unterst\u00fctzung zukommen lassen und sie in die Lage versetzen, der Wahrheit nachzugehen. Der Druck und die Drohungen gegen sie richten sich gegen den Zugang der Gesellschaft zu Informationen, die Pflicht, Rechenschaft abzulegen, und die allgemeinen Rechte und Freiheiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Anbetracht der Tatsache, dass Journalismus nicht nur ein Beruf ist, sondern ein Ausdruck sozialer Verantwortung und menschlicher W\u00fcrde, fordern wir lokale, nationale und internationale Akteure auf, dieses Umfeld vorzubereiten. Wir fordern die bedingungslose Freilassung von JournalistInnen, die in verschiedenen L\u00e4ndern hinter Gittern sitzen, und die Aufhebung von Gesetzen, die die Meinungsfreiheit kriminalisieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir gr\u00fc\u00dfen JournalistInnen, die ihren Beruf mit W\u00fcrde und unter Einhaltung universeller Grunds\u00e4tze aus\u00fcben, mit Liebe und Respekt. Am Welttag der Pressefreiheit weisen wir die \u00d6ffentlichkeit erneut darauf hin, dass wir mit allen MedienvertreterInnen solidarisch sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es sollte nicht vergessen werden, dass Grausamkeit sich von der Dunkelheit n\u00e4hrt, und JournalistInnen sind diejenigen, die Licht in die Dunkelheit bringen.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-cyan-blue-background-color has-background\" href=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/3_MAYIS_Taslak_Statement.docx\">T\u00fcrkisch<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-cyan-blue-background-color has-background\" href=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/3_Mayis_Statement_EN.docx\">Englisch<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-cyan-blue-background-color has-background\" href=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/3_Mayis_Statement_FR_.docx\">Franz\u00f6sisch<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der gemeinsame Punkt der Erkl\u00e4rungen, die von den Berufsverb\u00e4nden der Weltpresse am 3. Mai, dem Welttag der Pressefreiheit, ver\u00f6ffentlicht werden, ist stets die Forderung nach einem ,,Ende der Gewalt und Zensur gegen JournalistInnen&#8220;. Da dieser Aufforderung jedoch nicht ausreichend nachgekommen wird, werden zwei unverzichtbare Bestandteile von Demokratien, ,,die Meinungs- und Gedankenfreiheit und das Recht auf [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":25790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-normal","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"0","show_post_author":"0","show_post_author_image":"1","show_post_date":"0","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"2","show_author_box":"0","show_post_related":"1","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4624,5947,2868],"tags":[6644,6647,6648,6645,6646],"class_list":["post-25789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktivitaten","category-pressebriefing","category-schlagzeile","tag-3-mai-2","tag-russland","tag-ukraine-2","tag-welttag-der-pressefreiheit","tag-zensur-gegen-journalistinnen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Der gemeinsame Punkt der Erkl\u00e4rungen, die von den Berufsverb\u00e4nden der Weltpresse am 3. Mai, dem Welttag der Pressefreiheit, ver\u00f6ffentlicht werden, ist stets die Forderung nach einem ,,Ende der Gewalt und Zensur gegen JournalistInnen&#8220;. Da dieser Aufforderung jedoch nicht ausreichend nachgekommen wird, werden zwei unverzichtbare Bestandteile von Demokratien, ,,die Meinungs- und Gedankenfreiheit und das Recht auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T06:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1514\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten\",\"datePublished\":\"2022-05-03T06:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/\"},\"wordCount\":512,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gazeteci-zor-durum-1.jpeg\",\"keywords\":[\"3. Mai\",\"Russland\",\"Ukraine\",\"Welttag der Pressefreiheit\",\"Zensur gegen JournalistInnen\"],\"articleSection\":[\"Aktivit\u00e4ten\",\"Pressebriefing\",\"Schlagzeile\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/\",\"name\":\"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gazeteci-zor-durum-1.jpeg\",\"datePublished\":\"2022-05-03T06:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gazeteci-zor-durum-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gazeteci-zor-durum-1.jpeg\",\"width\":1514,\"height\":887},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/","og_locale":"de_DE","og_type":"article","og_title":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists","og_description":"Der gemeinsame Punkt der Erkl\u00e4rungen, die von den Berufsverb\u00e4nden der Weltpresse am 3. Mai, dem Welttag der Pressefreiheit, ver\u00f6ffentlicht werden, ist stets die Forderung nach einem ,,Ende der Gewalt und Zensur gegen JournalistInnen&#8220;. Da dieser Aufforderung jedoch nicht ausreichend nachgekommen wird, werden zwei unverzichtbare Bestandteile von Demokratien, ,,die Meinungs- und Gedankenfreiheit und das Recht auf [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2022-05-03T06:01:00+00:00","og_image":[{"width":1514,"height":887,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten","datePublished":"2022-05-03T06:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/"},"wordCount":512,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg","keywords":["3. Mai","Russland","Ukraine","Welttag der Pressefreiheit","Zensur gegen JournalistInnen"],"articleSection":["Aktivit\u00e4ten","Pressebriefing","Schlagzeile"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/","url":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/","name":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg","datePublished":"2022-05-03T06:01:00+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2022\/04\/gazeteci-zor-durum-1.jpeg","width":1514,"height":887},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/die-freiheit-der-medien-ein-wichtiger-bestandteil-des-lebenselixiers-demokratischer-staaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Die Freiheit der Medien: Ein wichtiger Bestandteil des Lebenselixiers demokratischer Staaten"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/25789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=25789"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/25789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/25790"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=25789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=25789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=25789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}