{"id":22824,"date":"2021-12-25T20:31:13","date_gmt":"2021-12-25T19:31:13","guid":{"rendered":"https:\/\/ijaev.org\/?p=22824"},"modified":"2021-12-30T21:07:47","modified_gmt":"2021-12-30T20:07:47","slug":"angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/","title":{"rendered":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">DR. KAMAL SIDO \/ NAHOST-REFERENT DER GESELLSCHAFT F\u00dcR BEDROHTE V\u00d6LKER (GFBV)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jedes Jahr am internationalen \u201eTag zur Beendigung der Strafl osigkeit bei Verbrechen gegen Journalisten\u201c (2. November) erinnern wir an das Schicksal von Jour\u0002nalist<em>innen, die in Haft oder frei sind, aber verschiedensten Bedrohungen bis hin zum Mord ausgesetzt werden. An diesem Tag machen wir auf die weltweit niedrige Verurteilungsrate f\u00fcr Gewaltverbrechen gegen Journalist<\/em>innen und Medien\u0002schaffende aufmerksam. Denn die T\u00e4ter kommen oft frei da\u0002von, wenn sie Journalist<em>innen angreifen. Nur jedes zehnte Verbrechen wird aufgekl\u00e4rt und geahndet. Dies f\u00fchrt dazu, dass junge Menschen sehr genau \u00fcberlegen, bevor sie sich f\u00fcr die Arbeit als politische Journalistin oder politischer Journalist entscheiden. Die Arbeit in diesem Bereich ist aber von gro\u00dfer Bedeutung. Medienschaffende spielen hier eine entscheiden\u0002de Rolle beim Informieren und Beeinfl ussen der \u00d6ffentlich\u0002keit zu wichtigen gesellschaftlichen Themen. Die Straffreiheit f\u00fcr Angriffe auf Medienschaffende hat besonders sch\u00e4dliche Auswirkungen auf das \u00f6ffentliche Bewusstsein. Weltweit nehmen Angriffe auf Medienschaffende zu. Diese Angriffe reichen von Cyber-Mobbing \u00fcber illegale In\u0002haftierungen bis hin zu Mord. Veranlasst werden sie durch die Regierungen der L\u00e4nder, aus denen Exilant<\/em>innen, auch oft Medienschaffende, stammen. So defi niert Freedom House den von Menschenrechtler<em>innen gepr\u00e4gten Begriff Transna\u0002tional Repression (dt. Transnationale Unterdr\u00fcckung). Gr\u00fcnde f\u00fcr die Zunahme dieser im 21. Jahrhundert sind vor allem der technische Fortschritt, die Kooperation zwischen Staaten ge\u0002gen Migrant<\/em>innen und der Mangel an internationalen Richt\u0002linien. Autorit\u00e4re Staaten nehmen Aktivit\u00e4ten der Exilant<em>in\u0002nen als Bedrohung f\u00fcr das von ihnen aufgebaute System im Heimatland wahr. Folglich greifen sie auf transnationale Unterdr\u00fcckung zur\u00fcck, um Exilant<\/em>innen einzusch\u00fcchtern und Exempel zu statuieren. Freedom House sch\u00e4tzt in einem Bericht vom Februar 2021, dass weltweit 3,5 Millionen Men\u0002schen von transnationaler Unterdr\u00fcckung betroffen sind.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formen der transnationalen Unterdr\u00fcckung k\u00f6nnen in vier Kategorien eingeteilt werden:<br>1) Direkte Angriffe wie physische Angriffe, Verschleppun\u0002gen und Attentate<br>2) Die Mithilfe anderer L\u00e4nder, die sich zum Beispiel durch unrechtm\u00e4\u00dfige Abschiebungen beteiligen<br>3) Mobilit\u00e4tsbeschr\u00e4nkungen wie die Annullierung von Reisep\u00e4ssen, die zu Inhaftierungen f\u00fchren kann<br>4) Drohungen aus der Ferne, zum Beispiel durch Cy\u0002ber-Mobbing oder die Bedrohung Angeh\u00f6riger im Heimatland. Auch die von der T\u00fcrkei ausgehende transnationale Un\u0002terdr\u00fcckung hat sich dem weltweiten Trend angeschlossen und stark zugenommen. Waren es fr\u00fcher Kurd<em>innen insbe\u0002sondere aus den Reihen der verbotenen kurdischen PKK, die vom t\u00fcrkischen Geheimdienst mit Hilfe \u201efreundlicher Staa\u0002ten\u201c in die T\u00fcrkei verschleppt oder entf\u00fchrt worden sind, so sind es heute vermehrt die Anh\u00e4nger<\/em>innen des im amerika\u0002nischen Exil lebenden t\u00fcrkischen Predigers Fethullah G\u00fclen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die t\u00fcrkische Regierung unter Recep Tayyip Erdo\u011fan wirft G\u00fclen vor hinter dem Putschversuch von 2016 zu stecken, der einen enormen und geographisch weitreichenden Anstieg der transnationalen Unterdr\u00fcckung durch die t\u00fcrkische Regie\u0002rung ausl\u00f6ste: In 31 L\u00e4ndern, sowohl in Asien, Afrika, im Nahen<br>Osten, Nord- und S\u00fcdamerika und Europa wurden Exilant<em>in\u0002nen Opfer dieser. W\u00e4hrend Russlands Kampagne der transnationalen Unter\u0002dr\u00fcckung stark auf Attentate ausgerichtet ist und China sich allen vier Kategorien der transnationalen Unterdr\u00fcckung be\u0002dient, ist die T\u00fcrkei f\u00fchrend was Verschleppungen angeht. In den letzten Jahren richteten sich die Angriffe der t\u00fcr\u0002kischen Regierung gr\u00f6\u00dftenteils gegen Personen mit Verbin\u0002dung zur G\u00fclen-Bewegung. Auch diese Bewegung wird von der Regierung in der T\u00fcrkei als \u201eterroristisch\u201c eingestuft und f\u00fcr den Putschversuch 2016 verantwortlich gemacht. In Nach\u0002forschungen von Freedom House konnten 58 F\u00e4lle von Ver\u0002schleppungen, willk\u00fcrlichen Festnahmen und Folter in 17 L\u00e4ndern seit 2014 identifiziert werden. Zahlen der UN und der t\u00fcrkischen Regierung selbst sind jedoch circa doppelt so gro\u00df, wom\u00f6glich da sich viele F\u00e4lle au\u00dferhalb der \u00d6ffentlichkeit abspielen. Ohne klaren legalen Prozess werden Exilant<\/em>innen in ihrem Aufenthaltsland festgenommen und an die T\u00fcrkei ausgeliefert. Derartige F\u00e4lle ereigneten sich beispielsweise im Libanon und in Kirgisistan in Zusammenarbeit mit den jewei\u0002ligen Regierungen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch die T\u00fcrkei verheimlicht ihre Entf\u00fchrungskampa\u0002gne nicht. Die Opfer werden stolz in den Medien pr\u00e4sentiert, denn die Festnahmen werden als legitime Mittel der Terro\u0002rismusbek\u00e4mpfung dargestellt. So ver\u00f6ffentlicht die Pro-Re\u0002gierungs-Zeitung Daily Sabah regelm\u00e4\u00dfig Artikel zur Ent\u0002f\u00fchrungskampagne unter der Rubrik War on Terror. Auch die G\u00fclen-Bewegung wurde nun ebenfalls als Terrororganisation eingestuft, womit diverse Formen der transnationalen Unter\u0002dr\u00fcckung von Mitgliedern oder scheinbar Verb\u00fcndeten der Bewegung gerechtfertigt werden. Alle 110 F\u00e4lle physischer transnationaler Unterdr\u00fcckung durch die t\u00fcrkische Regie\u0002rung, die Freedom House feststellen konnte, stehen in Verbin\u0002dung mit einem Terrorismusvorwurf.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abschlie\u00dfend m\u00f6chte ich auf Praktiken der t\u00fcrkischen Po\u0002lizei im Umgang mit inhaftierten Journalist*innen aufmerk\u0002sam machen. Der Journalist Ibrahim Karaye\u011fen wurde w\u00e4h\u0002rend der U-Haft im Polizeipr\u00e4sidium in Antalya von Polizisten beschimpf und bedroht. Er wurde in einen Raum gesperrt, in dem F\u00e4kalien waren. Ihm wurde kein Gang zur Toilette er\u0002laubt. W\u00e4hrend der Haftzeit durfte der chronisch kranke Mann drei Monate keinen Arzt sehen. Er bekam seine Medikamente nicht und seine Nieren funktionierten nur noch zu 45 Prozent.<br>Nach einer OP wurde der Mann im Winter nackt in einen Raum<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">bei offenem Fenster gesteckt, \u201eSie wollten, dass ich sterbe,\u201c sagte er. Nach der schnellen OP musste er wieder in seine Ge\u0002f\u00e4ngnis-Zelle, obwohl er nicht einmal allein aufs WC konnte. Die Mitinsassen mussten ihm sieben Tage beim Toilettengang helfen. Sein Rechtsanwalt durfte ihn nur selten besuchen. Bei<br>den Besuchen durch den Rechtsanwalt war immer ein W\u00e4chter dabei, der die Gespr\u00e4che aufzeichnete. Auch seine Frau durfte ihn nur selten besuchen. Auch diese Gespr\u00e4che wurden auf\u0002gezeichnet. Die Inhalte dieser Gespr\u00e4che waren auch Gegen\u0002stand der Anklage.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c4hnliches erlebte der Journalist Y\u00fcksel Durgut. W\u00e4hrend seiner Haft musste er am Herzen operiert werden. Nach seiner OP wurde er in ein Zimmer gesteckt, in dem Kranke mit anste\u0002ckenden Krankheiten lagen. \u201eDas Bett war verdreckt und die Laken waren mit Blut verdreckt\u201c, sagt der Journalist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DR. KAMAL SIDO \/ NAHOST-REFERENT DER GESELLSCHAFT F\u00dcR BEDROHTE V\u00d6LKER (GFBV)<\/p>\n","protected":false},"author":17,"featured_media":23831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676,4623],"tags":[6218,5190,6217,4694,5496],"class_list":["post-22824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","category-nachrichten","tag-bedroehte-voelker","tag-dr-kamal-sido-3","tag-gfbv-4","tag-international-journalists-association","tag-journalist-post-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists\" \/>\n<meta property=\"og:description\" content=\"DR. KAMAL SIDO \/ NAHOST-REFERENT DER GESELLSCHAFT F\u00dcR BEDROHTE V\u00d6LKER (GFBV)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-25T19:31:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-30T20:07:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden\",\"datePublished\":\"2021-12-25T19:31:13+00:00\",\"dateModified\":\"2021-12-30T20:07:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/\"},\"wordCount\":1017,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Kamal_Sido_jp1_DE-1.jpg\",\"keywords\":[\"Bedr\u00f6hte V\u00f6lker\",\"Dr. Kamal Sido\",\"GFBV\",\"International Journalists Association\",\"Journalist Post\"],\"articleSection\":[\"Authoren\",\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/\",\"name\":\"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Kamal_Sido_jp1_DE-1.jpg\",\"datePublished\":\"2021-12-25T19:31:13+00:00\",\"dateModified\":\"2021-12-30T20:07:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Kamal_Sido_jp1_DE-1.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Kamal_Sido_jp1_DE-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/","og_locale":"de_DE","og_type":"article","og_title":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists","og_description":"DR. KAMAL SIDO \/ NAHOST-REFERENT DER GESELLSCHAFT F\u00dcR BEDROHTE V\u00d6LKER (GFBV)","og_url":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-25T19:31:13+00:00","article_modified_time":"2021-12-30T20:07:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden","datePublished":"2021-12-25T19:31:13+00:00","dateModified":"2021-12-30T20:07:47+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/"},"wordCount":1017,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg","keywords":["Bedr\u00f6hte V\u00f6lker","Dr. Kamal Sido","GFBV","International Journalists Association","Journalist Post"],"articleSection":["Authoren","Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/","url":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/","name":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg","datePublished":"2021-12-25T19:31:13+00:00","dateModified":"2021-12-30T20:07:47+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Kamal_Sido_jp1_DE-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/angriff-e-auf-medienschaff-ende-in-der-tuerkei-muessen-beendet-werden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Angriff e auf Medienschaff ende in der T\u00fcrkei m\u00fcssen beendet werden"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=22824"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/23831"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=22824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=22824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=22824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}