{"id":22275,"date":"2021-12-15T16:58:56","date_gmt":"2021-12-15T15:58:56","guid":{"rendered":"https:\/\/ijaev.org\/?p=22275"},"modified":"2021-12-30T21:13:38","modified_gmt":"2021-12-30T20:13:38","slug":"freiheit-fuer-journalisten","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/","title":{"rendered":"Freiheit f\u00fcr Journalisten!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">VON MOGENS BLICHER BJERREG\u00c5RD \/ PR\u00c4SIDENT DER EUROP\u00c4ISCHEN JOURNALISTENVEREINIGUNG<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr als 75 Journalisten sitzen in Europa hinter Gittern und einige warten auf das Gerichtsverfahren. Diese Situa\u0002tion ist nicht nur erschreckend f\u00fcr die Journalisten, die nur wegen ihrer Arbeit zu Gef\u00e4ngnisstrafen verurteilt wurden, sondern sie ist auch zutiefst problematisch f\u00fcr die Pressefreiheit, da jede Art<br>von Verletzung von Journalisten einen abschreckenden Effekt auf Journalismus hat. Und nicht zuletzt wird dadurch die Demokratie untergraben und ein gro\u00dfes Risiko f\u00fcr die Zukunft des friedlichen Europas geschafft.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit vielen Jahren gilt die T\u00fcrkei als das gr\u00f6\u00dfte Gef\u00e4ngnis f\u00fcr Journalisten, was leider immer noch der Fall ist, wenn 50 Journalis\u0002ten und Medienmitarbeiter im Gef\u00e4ngnis sitzen, so das letzte Up\u0002date der Europ\u00e4ischen Journalistenf\u00f6deration. Darauf sollten wir auf eine Reihe von Bloggern, Schriftstellern und Menschenrechts\u0002verteidigern eingehen. Seit Jahren sind wir alle in diesem Fall aktiv, und wie ist es an der Zeit, neue Initiativen und Mechanismen zu<br>entwickeln, um die Situation in der T\u00fcrkei zu \u00e4ndern?<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heute fordert Belarus die T\u00fcrkei in dieser bedauerlichen Ent\u0002wicklung heraus. Die wei\u00dfrussische Diktatur hat willk\u00fcrlich ihre Journalisten zu Gef\u00e4ngnisstrafen verurteilt. 10 haben Urteile erhal\u0002ten, und viele weitere warten auf ihren Prozess oder einfach auf die n\u00e4chsten Schritte. Wie wir in der T\u00fcrkei gesehen haben, wie Journa\u0002listen verhaftet, angeklagt und wegen Tweets oder erfundener An\u0002schuldigungen inhaftiert wurden, riskieren Journalisten in Wei\u00df\u0002russland, weil sie die Wahrheit gesagt haben, wie es bei einer jungen Journalistin der Fall war, die die \u00d6ffentlichkeit dar\u00fcber informierte,<br>dass ein get\u00f6teter B\u00fcrger nicht von Alkohol betroffen war, wof\u00fcr er angeklagt wurde. Ihr \u201cVerbrechen\u201d bestand darin, pers\u00f6nliche Infor\u0002mationen preiszugeben.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Russland und Aserbaidschan sind zwei weitere L\u00e4nder mit inhaftierten Journalisten in Europa. Andere L\u00e4nder nutzen jedoch andere Instrumente, um Journalisten zum Schweigen zu bringen. Die so genannten SLAPP (Strategic Lawsuits Against Public Partici\u0002pation), besch\u00e4ftigen Hunderte von Journalisten, die sich mit ihren eigenen F\u00e4llen besch\u00e4ftigen, und stehlen so ihre Zeit f\u00fcr ernsthaf\u0002ten Journalismus. Eine dritte und gef\u00e4hrliche Methode, Journalisten und freie Medien zum Schweigen zu bringen, ist das Wort, n\u00e4mlich wenn ins\u0002besondere Pr\u00e4sidenten und Ministerpr\u00e4sidenten Journalisten ver\u0002bal angreifen. Das haben wir in mehreren mittelosteurop\u00e4ischen L\u00e4ndern gesehen. Solche Worte sind wichtig, weil politische F\u00fchrer mit ihrer Rhetorik de facto Hass auf Journalisten legalisieren, was immer die erste Welle vor physischen Angriffen und schlimmsten\u0002falls Mordung ist.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend all unserer Geschichte autorit\u00e4re Regime die freien Medien unterdr\u00fcckt haben, indem sie die Kontrolle \u00fcber das Wort hatten, das immer das erste Opfer in einem Konflikt oder Krieg war. Andererseits ist freier und unabh\u00e4ngiger Journalismus eine Voraus\u0002setzung f\u00fcr eine florierende Demokratie, und deshalb begr\u00fc\u00dfen wir, von der Europ\u00e4ischen Journalistenf\u00f6deration, den EU-Aktionsplan Demokratie zur Bek\u00e4mpfung der Verletzung freier Medien sehr.<br>Deshalb sollten wir in Europa anl\u00e4sslich des Welttages der Pressefreiheit am 3. Mai den Aktionsplan weiterverfolgen, der un\u0002sere Regierungen ermutigt, die Gew\u00e4hrleistung der Freiheit von Journalisten zu verst\u00e4rken; nationale Aktionspl\u00e4ne f\u00fcr die Sicher\u0002heit von Journalisten unter Einbeziehung aller Beteiligten, die Teil der L\u00f6sung sein sollten; Unterst\u00fctzung der EU in einer Richtlinie gegen die SLAPP; Gew\u00e4hrleistung von Selbstregulierungsmecha\u0002nismen in allen europ\u00e4ischen L\u00e4ndern; Einf\u00fchrung von Prinzipien der Waffenausdehnung, die sowohl Politiker als auch Oligarchen dazu auffordern, sich aus dem Nachrichtenraum herauszuhalten.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber wir m\u00fcssen hoch hinaus. Als Journalisten haben wir uns stets f\u00fcr unsere Werte eingesetzt, die nicht mit der Politik vermischt wurden, sondern als \u00e4u\u00dferst wichtiger W\u00e4chter in jeder Gesellschaft standen. Ohne unsere Rolle zu gef\u00e4hrden, m\u00fcssen wir f\u00fcr die Zu\u0002kunft st\u00e4rker auf die Entwicklung der Demokratie achten. Wir be\u0002teiligen uns bereits an der so genannten Medienkompetenz, also sollten wir jetzt mit unserer Rolle im Hinterkopf hoch hinaus ge\u0002hen und unsere Rolle spielen, bei dem, was wir Demokratie-Kom\u0002petenz nennen k\u00f6nnten und sollten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VON MOGENS BLICHER BJERREG\u00c5RD \/ PR\u00c4SIDENT DER EUROP\u00c4ISCHEN JOURNALISTENVEREINIGUNG Mehr als 75 Journalisten sitzen in Europa hinter Gittern und einige warten auf das Gerichtsverfahren. Diese Situa\u0002tion ist nicht nur erschreckend f\u00fcr die Journalisten, die nur wegen ihrer Arbeit zu Gef\u00e4ngnisstrafen verurteilt wurden, sondern sie ist auch zutiefst problematisch f\u00fcr die Pressefreiheit, da jede Artvon Verletzung [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":23835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[5943,4676],"tags":[4694,5496,6075],"class_list":["post-22275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse","category-author","tag-international-journalists-association","tag-journalist-post-2","tag-von-mogens-blicher-bjerregard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freiheit f\u00fcr Journalisten! - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freiheit f\u00fcr Journalisten! - International Journalists\" \/>\n<meta property=\"og:description\" content=\"VON MOGENS BLICHER BJERREG\u00c5RD \/ PR\u00c4SIDENT DER EUROP\u00c4ISCHEN JOURNALISTENVEREINIGUNG Mehr als 75 Journalisten sitzen in Europa hinter Gittern und einige warten auf das Gerichtsverfahren. Diese Situa\u0002tion ist nicht nur erschreckend f\u00fcr die Journalisten, die nur wegen ihrer Arbeit zu Gef\u00e4ngnisstrafen verurteilt wurden, sondern sie ist auch zutiefst problematisch f\u00fcr die Pressefreiheit, da jede Artvon Verletzung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T15:58:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-30T20:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Freiheit f\u00fcr Journalisten!\",\"datePublished\":\"2021-12-15T15:58:56+00:00\",\"dateModified\":\"2021-12-30T20:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mogens_Blachir_jp1_DE-1.jpg\",\"keywords\":[\"International Journalists Association\",\"Journalist Post\",\"Von Mogens Blicher Bjerregard\"],\"articleSection\":[\"Analyse\",\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/\",\"name\":\"Freiheit f\u00fcr Journalisten! - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mogens_Blachir_jp1_DE-1.jpg\",\"datePublished\":\"2021-12-15T15:58:56+00:00\",\"dateModified\":\"2021-12-30T20:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mogens_Blachir_jp1_DE-1.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mogens_Blachir_jp1_DE-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/freiheit-fuer-journalisten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Freiheit f\u00fcr Journalisten!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freiheit f\u00fcr Journalisten! - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/","og_locale":"de_DE","og_type":"article","og_title":"Freiheit f\u00fcr Journalisten! - International Journalists","og_description":"VON MOGENS BLICHER BJERREG\u00c5RD \/ PR\u00c4SIDENT DER EUROP\u00c4ISCHEN JOURNALISTENVEREINIGUNG Mehr als 75 Journalisten sitzen in Europa hinter Gittern und einige warten auf das Gerichtsverfahren. Diese Situa\u0002tion ist nicht nur erschreckend f\u00fcr die Journalisten, die nur wegen ihrer Arbeit zu Gef\u00e4ngnisstrafen verurteilt wurden, sondern sie ist auch zutiefst problematisch f\u00fcr die Pressefreiheit, da jede Artvon Verletzung [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-15T15:58:56+00:00","article_modified_time":"2021-12-30T20:13:38+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Freiheit f\u00fcr Journalisten!","datePublished":"2021-12-15T15:58:56+00:00","dateModified":"2021-12-30T20:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/"},"wordCount":682,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg","keywords":["International Journalists Association","Journalist Post","Von Mogens Blicher Bjerregard"],"articleSection":["Analyse","Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/","url":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/","name":"Freiheit f\u00fcr Journalisten! - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg","datePublished":"2021-12-15T15:58:56+00:00","dateModified":"2021-12-30T20:13:38+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Mogens_Blachir_jp1_DE-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/freiheit-fuer-journalisten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Freiheit f\u00fcr Journalisten!"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=22275"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/23835"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=22275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=22275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=22275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}