{"id":22126,"date":"2021-12-13T12:54:28","date_gmt":"2021-12-13T11:54:28","guid":{"rendered":"https:\/\/ijaev.org\/?p=22126"},"modified":"2021-12-13T12:54:30","modified_gmt":"2021-12-13T11:54:30","slug":"es-war-nicht-der-milchmann-der-an-die-tuer-klopfte","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/","title":{"rendered":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">NUR EREN KILIN\u00c7 \/ Absolvent der Atat\u00fcrk Universit\u00e4t, Fakult\u00e4t f\u00fcr Kommunikation, war der politische Nachrichtenredakteur der Zeitung Yeni Asya. Sie wurde am 1. M\u00e4rz 2017 als Journalistin mit einem gelben Pres\u0002seausweis in der T\u00fcrkei verhaftet. Sie wurde am 21. Februar 2018 nach einer Strafe von 7 Jahren und 6 Monaten Gef\u00e4ngnis und Hausarrest entlassen. W\u00e4hrend sie im Ge\u0002f\u00e4ngnis war, wurde ihr Buch \u201cThree Branch of Daisies\u201d, bestehend aus Briefen von<br>Menschen im Gef\u00e4ngnis, von der Yeni Asya Press ver\u00f6ffentlicht. Sie erschien erneut vor Gericht wegen des Vorwurfs, das Buch sei eine \u201cPropaganda der Terrororganisation\u201d. Der Journalist musste aufgrund unendli\u0002chen Drucks nach Deutschland fliehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">inston Churchill beschreibt Demokratie wie folgt: \u201eWenn es morgens um 06.00 an meiner T\u00fcr l\u00e4utet und ich kann sicher sein, dass es der Milchmann ist, dann wei\u00df ich, dass ich in einer Demokratie lebe\u201c.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich war eine 25-j\u00e4hrige Journalistin (Jahr 2017), als ich die Situ\u0002ation erlebte, die Churchill in Bezug auf Demokratie beschreiben wollte. Am Feierabend verlie\u00df ich die Redaktion der Zeitung, in der ich zu dieser Zeit arbeitete und nach einem s\u00fc\u00dfen Abendspazier\u0002gang mit dem Traum von meiner Hochzeit, der zwei Monate sp\u00e4ter sein wird, kam ich gegen 19 Uhr in meine Wohnung in der ich allei\u0002ne lebte. Zu Hause setzte ich meine Arbeit zum Putschversuch vom 15. Juli fort, das von Diktator Erdogan geschrieben und inszeniert wurde. Ich musste arbeiten, weil die Nachrichten, die in meinen Posteingang fielen, mich verbl\u00fcfften. Die Familien der 18-j\u00e4hri\u0002gen Soldaten, die f\u00fcr den Putschversuch am 15. Juli verantwortlich waren, und die Familien der \u00c4rzte und Lehrer, die \u00fcber Nacht von Erdo\u011fan zu Terroristen erkl\u00e4rt wurden, schickten uns Journalisten Hunderte von E-Mails. Ich recherchierte auch diese E-Mails, be\u0002sorgte mir die erforderlichen Gerichtsdokumente und bereitete ein Buch vor. Ich hatte zwei M\u00f6glichkeiten: Mir w\u00e4re es gleichg\u00fcl\u0002tig, was geschah, ich w\u00fcrde keine eingehenden E-Mails lesen und keine politischen Nachrichten schreiben. Oder als Voraussetzung f\u00fcr meinen Beruf und meine Menschlichkeit w\u00fcrde ich die Wahr\u0002heiten um jeden Preis schreiben.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DAS ERSTE ZIEL DER POLIZEI WAREN MEINE B\u00dcCHER<br>In der Zeitung, f\u00fcr die ich gearbeitet habe, machte mein Artikel mit dem Titel \u201cDer Ausnahmezustand ist am 28. Februar vorbei\u201d Schlagzeilen. Erdogans Social-Media-Trolle drohten besonders nach diesen Schlagzeilen. In meinem Briefkasten befanden sich jetzt Drohnachrichten, und in meinen Gedanken die unschuldigen Men\u0002schen, die von Erdo\u011fan zu Feinden gemacht und eingesperrt wur\u0002den. Aus meinem Schlaf, in diese Gedanken versunken, wachte ich<br>gegen 3 Uhr morgens auf, als meine T\u00fcr um Mitternacht klopfte. Sie schlugen heftig gegen meine Holzt\u00fcr und schrien laut. Es war nicht der Milchmann, von dem Churchill sprach, der an meine T\u00fcr klopf\u0002te! Das war offensichtlich. Als ich die T\u00fcr \u00f6ffnete, griffen Erdogans 8 m\u00e4nnliche Polizisten sofort mein 40 Quadratmeter gro\u00dfes Haus an.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die erste Aufgabe dieser Polizisten, die mir nicht einmal das Anzie\u0002hen erlaubten, war es, meine B\u00fccher anzugreifen\u2026 Ja! Ich beschreibe diese Aktion als anst\u00f6\u00dfig und m\u00f6chte dieser Aktion ihren gruseligen Ausdruck hinzuf\u00fcgen. Das erste, was mir in den Sinn kam, waren die Worte von Alberto Manguel, als ich diese Leute sah, die meine fast 400 B\u00fccher und Manuskriptbriefe in meinem Zimmer gnadenlos verpr\u00fcgelten und das terroristische Verbrechen aus den B\u00fcchern ex\u0002trahieren wollten: \u201cUnter den vom Menschen erfundenen Gegen\u0002st\u00e4nden sind der gr\u00f6\u00dfte Feind der Diktatoren B\u00fccher.\u201d<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NACKTE SUCHFOLTER<br>Nachdem ich ein letztes Mal mein gepl\u00fcndertes Haus, mei\u0002ne auf dem Boden verstreuten B\u00fccher und meine unvollendeten Hochzeitsvorbereitungen angesehen hatte, verlie\u00df ich mein Haus und verabschiedete mich von meinem 40 Quadratmeter gro\u00dfen Leben unter 8 m\u00e4nnlichen Polizisten. Das gewaltt\u00e4tige Verhalten der Polizei war ein kleines Spiegelbild der Wut des Diktators. Ich ver\u0002stand, dass ich mich nicht von meinen Azaleenbl\u00fcten verabschieden konnte, die sich zum \u00d6ffnen vorbereiteten, und meine blumenher\u0002zige Mutter beobachtete meinen Weg. Meine Reise, die nachts be\u0002gann, wurde im Istanbul Bak\u0131rk\u00f6y Gef\u00e4ngnis fortgesetzt, nachdem meine Haftzeit die Polizeistation gef\u00fcllt hatte, in die ich gebracht wurde. Ich wusste nicht, was mit mir in dem kleinen Raum passieren w\u00fcrde, in den ich gebracht wurde, nachdem ich ins Gef\u00e4ngnis einge\u0002liefert worden war. Ich wurde von 2-3 weiblichen Wachen begleitet von Lachen und ihrem t\u00e4glichen Klatsch gefoltert und nackt durch\u0002sucht. Sp\u00e4ter, in der Zelle, in die ich gebracht wurde, wurde mir klar, dass ich nicht die einzige war, der dieser Folter ausgesetzt war. Die Richterin \u00d6.N, die sich in der n\u00e4chsten Zelle befindet und mit dem wir von Glas zu Glas geschrien haben, sagte auch, sie sei dieser Folter schon oft ausgesetzt gewesen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">WAS WOLLEN SIE VON DEN BABYS?<br>Offensichtlich war es am schwierigsten, ein politischer Gefan\u0002gener im Gef\u00e4ngnis zu sein. Nach den Arbeitszeiten, die mit dem ersten Licht des Tages begannen, gingen forensische Kriminelle (Diebe usw.) ins Fitnessstudio, in die Bibliothek und in den Malun\u0002terricht. Ihr freudiges Lachen hallte in den kalten Korridoren des Ge\u0002f\u00e4ngnisses wider. Solche Aktivit\u00e4ten waren f\u00fcr politische Gefangene verboten, die sich in derselben Situation wie mich befanden. Leider<br>wurden auch gefangene Babys in diese Kategorie aufgenommen!<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du hast nicht falsch gelesen, ja! W\u00e4hrend die Kinder von Frauen, die wegen Straftaten inhaftiert waren, das Recht hatten, in einen Kin\u0002dergarten zu gehen, hatten die Kinder in unserer Zelle kein solches Recht. Am Morgen erleuchteten die Ger\u00e4usche der Kinder, die in den Kindergarten gingen, das Gef\u00e4ngnis auf der Insel wie das Zwitschern eines Vogels\u2026 Ich mied die Fragen meines 5 j\u00e4hrigen besten Freun\u0002des S. \u201eWer sind diese Kinder? Ich m\u00f6chte auch mit diesen Kindern spielen?\u201c Die Beantwortung dieser Fragen war schlimmer als alle Folterungen und Rechtsverletzungen, denen ich ausgesetzt war.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DER \u201cVERBRECHER\u201d, DER NICHT EINMAL ALLEINE AUF DIE TOILETTE GEHEN KANN<br>Eine andere Sache, die meine Schl\u00e4fen pochte, waren die \u00e4lteren und kranken Frauen in unserer Zelle. Es ist unm\u00f6glich f\u00fcr mich, F. zu vergessen, der an Alzheimer leidet und leise in den Ecken weint und sagt: \u201cWo bin ich jetzt, bring mich zu meinen Enkelkindern.\u201d<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trotz der Jahre, die vergangen sind, ist diese Stimme immer noch in meinen Ohren und Albtr\u00e4umen. Es lag an anderen Gefangenen, die\u0002se Frau zu heben, die aufgrund verschiedener Krankheiten in Taille, Herz und H\u00e4nden ihre pers\u00f6nlichen Bed\u00fcrfnisse nicht befriedigen konnte und von Zeit zu Zeit auf die Toilette fiel. Erdogan; Was wollte er von dieser Frau, die nicht einmal die f\u00fcr ihren Gericht notwendi\u0002gen Verteidigungen schreiben konnte, nicht einmal alleine auf die Toilette gehen oder duschen konnte? Was war Erdogans Platz im Putschtheater? Das einzige Verbrechen dieser Frau besteht darin, als<br>Freiwillige in einem von Erdogan feindlichen Korankurs zu arbeiten und Essen f\u00fcr arme Studenten zu kochen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MEIN FR\u00dcHLING IN PETERSILIE, MEIN FRIEDEN<br>Inmitten der endlosen Tage, des Betons und des Drucks, ver\u0002suchte ich, kleine Sch\u00f6nheiten zu erschaffen, die f\u00fcr mich und andere Gefangene eine Aufmunterung sein sollten. Ich stellte einen Haufen Petersilie, den ich aus der Gef\u00e4ngniskantine be\u0002stellt hatte, in meine Vase, die ich aus einer Plastikflasche ge\u0002macht hatte, und schaute auf das Gr\u00fcne, in die ich mich verliebt hatte. In diesem erdlosen, farblosen Folternest war es, als w\u00fcrde man Veilchen betrachten. Bis die Wachen das bemerkten \u2026 Der Wachmann, der mit seinen schmutzigen H\u00e4nden und schmut\u0002zigen Herzen meine Plastikflaschenvase und Petersilie ergriff, schrie mich an; \u201ePetersilie wird zum Verzehr verkauft. Das kannst du nicht aufheben \u201c, sagte er. Diese wildherzigen Menschen, die selbst von der Hoffnung auf das Gr\u00fcn der Petersilie geplagt wur\u0002den, waren nat\u00fcrlich zum Verlieren verurteilt.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ERDOGANS GIFT IST DIE MEDIENARMEE<br>Nach meiner 357-t\u00e4gigen Haft wurde ich nach einer 7-j\u00e4hrigen und 6-monatigen Haftstrafe mit den Spuren von Folter in meinem Geist und meinem K\u00f6rper aus dem Gef\u00e4ngnis entlassen. Als ich meinen ersten Schritt an der Gef\u00e4ngnist\u00fcr in Richtung Freiheit machte schrie ich: \u201eIch bin jetzt vor der T\u00fcr. Aber hinter dieser Ei\u0002sent\u00fcr in der Zelle sind Babys, alte und kranke Frauen. Ich sagte: \u201cIch werde gl\u00fccklich sein, wenn sie auch frei sind.\u201d Babys und kran\u0002ke Frauen mit diesen grausamen Menschen zur\u00fcckzulassen, die sogar das Gr\u00fcn der Petersilie hassen, machte mich traurig. Wenn es um die T\u00fcrkei, Gef\u00e4ngnisse, Menschenrechtsverletzungen und Diktator Erdogan geht, reichen Seiten, Tage und Monate nicht aus, um alles zu erz\u00e4hlen. Ungef\u00e4hr 5 Jahre sind seit dem Putschtheater vom 15. Juli 2016 und meiner 357-t\u00e4gigen Haft vergangen. Was ist in diesen 5 Jahren passiert? Nach Angaben von RSF Data, gr\u00fcndete Erdogan in der T\u00fcrkei, das Land mit dem weltweit gr\u00f6\u00dften Gef\u00e4ng\u0002nis f\u00fcr Journalisten, seine eigene Medienarmee und f\u00fchrte seine Entschlossenheit mit der Macht der von ihm vergifteten Men\u0002schen weiter fort. Ray Bradbury sagte folgendes in Fahrenheit 451: \u201eSie k\u00f6nnen die B\u00fccher schlie\u00dfen, indem Sie\u201a Moment mal warte \u2018sagen. Aber nachdem der Fernseher einen Samen in den Raum pflanzt, konnte sich dann jemand aus seinem Griff retten? \u201c<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Hoffnung f\u00fcr die Freiheit der Babys und kranken Gefangenen, die in den Gef\u00e4ngnissen um ihr Leben k\u00e4mpfen..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUR EREN KILIN\u00c7 \/ Absolvent der Atat\u00fcrk Universit\u00e4t, Fakult\u00e4t f\u00fcr Kommunikation, war der politische Nachrichtenredakteur der Zeitung Yeni Asya. Sie wurde am 1. M\u00e4rz 2017 als Journalistin mit einem gelben Pres\u0002seausweis in der T\u00fcrkei verhaftet. Sie wurde am 21. Februar 2018 nach einer Strafe von 7 Jahren und 6 Monaten Gef\u00e4ngnis und Hausarrest entlassen. W\u00e4hrend [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":22127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676],"tags":[4694,5496,6052],"class_list":["post-22126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","tag-international-journalists-association","tag-journalist-post-2","tag-nur-erener-kilinc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists\" \/>\n<meta property=\"og:description\" content=\"NUR EREN KILIN\u00c7 \/ Absolvent der Atat\u00fcrk Universit\u00e4t, Fakult\u00e4t f\u00fcr Kommunikation, war der politische Nachrichtenredakteur der Zeitung Yeni Asya. Sie wurde am 1. M\u00e4rz 2017 als Journalistin mit einem gelben Pres\u0002seausweis in der T\u00fcrkei verhaftet. Sie wurde am 21. Februar 2018 nach einer Strafe von 7 Jahren und 6 Monaten Gef\u00e4ngnis und Hausarrest entlassen. W\u00e4hrend [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-13T11:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-13T11:54:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE!\",\"datePublished\":\"2021-12-13T11:54:28+00:00\",\"dateModified\":\"2021-12-13T11:54:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/\"},\"wordCount\":1548,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Nur_Erener_Kilic_jp2.jpg\",\"keywords\":[\"International Journalists Association\",\"Journalist Post\",\"Nur Erener K\u0131l\u0131n\u00e7\"],\"articleSection\":[\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/\",\"name\":\"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Nur_Erener_Kilic_jp2.jpg\",\"datePublished\":\"2021-12-13T11:54:28+00:00\",\"dateModified\":\"2021-12-13T11:54:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Nur_Erener_Kilic_jp2.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Nur_Erener_Kilic_jp2.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/","og_locale":"de_DE","og_type":"article","og_title":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists","og_description":"NUR EREN KILIN\u00c7 \/ Absolvent der Atat\u00fcrk Universit\u00e4t, Fakult\u00e4t f\u00fcr Kommunikation, war der politische Nachrichtenredakteur der Zeitung Yeni Asya. Sie wurde am 1. M\u00e4rz 2017 als Journalistin mit einem gelben Pres\u0002seausweis in der T\u00fcrkei verhaftet. Sie wurde am 21. Februar 2018 nach einer Strafe von 7 Jahren und 6 Monaten Gef\u00e4ngnis und Hausarrest entlassen. W\u00e4hrend [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-13T11:54:28+00:00","article_modified_time":"2021-12-13T11:54:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE!","datePublished":"2021-12-13T11:54:28+00:00","dateModified":"2021-12-13T11:54:30+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/"},"wordCount":1548,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg","keywords":["International Journalists Association","Journalist Post","Nur Erener K\u0131l\u0131n\u00e7"],"articleSection":["Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/","url":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/","name":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE! - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg","datePublished":"2021-12-13T11:54:28+00:00","dateModified":"2021-12-13T11:54:30+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Nur_Erener_Kilic_jp2.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/es-war-nicht-der-milchmann-der-an-die-tuer-klopfte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"ES WAR NICHT DER MILCHMANN, DER AN DIE T\u00dcR KLOPFTE!"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=22126"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/22126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/22127"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=22126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=22126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=22126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}