{"id":21750,"date":"2021-12-08T12:50:45","date_gmt":"2021-12-08T11:50:45","guid":{"rendered":"https:\/\/ijaev.org\/?p=21750"},"modified":"2021-12-08T12:50:47","modified_gmt":"2021-12-08T11:50:47","slug":"es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/","title":{"rendered":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201eDie Leute, die im Kessel auf mich gewartet haben, die mich zu Tode steinigen wollten, nur wegen der Anschuldi\u0002gungen der Regierung. Die Leute, die nichts \u00fcber mich wissen! Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ARZU YILDIZ EXILJOURNALISTIN \/ KANADA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bin seit 2003 eine unabh\u00e4ngige Journalistin. Ich habe zwischen 2009 und 2016 Kriminalit\u00e4tsberichte erstellt. Ich wei\u00df nicht, was das Konzept des \u201eGerichtsgeb\u00e4udes\u201c in den Gedanken anderer hervorruft. F\u00fcr mich ist es gleichbedeutend mit einem Messer im Herzen und mit Schmerz, Verzweiflung, Tr\u00e4nen, Hoffnungslosigkeit, Trauer, Trauer und jedem anderen Gef\u00fchl, durch das dieses Geb\u00e4ude errichtet wur\u0002de..Die Gerichtsgeb\u00e4ude sind wie Friedh\u00f6fe. Sie sind die Treffpunkte von den praktisch lebendig in den Gef\u00e4ngnissen Begrabenen, weil sie jemanden get\u00f6tet haben, und der n\u00e4chsten Angeh\u00f6rigen der Opfer. Eine Mutter trauert um einen Sohn, den sie gerade begraben hat, und eine andere Mutter brennt im Herzen um einen anderen, der gerade<br>zum M\u00f6rder geworden ist. Sie w\u00fcrden junge Leute sehen, die zum Ge\u0002richtsgeb\u00e4ude rennen, nachdem sie die Inhaftierung ihres Vaters ge\u0002h\u00f6rt haben. Die W\u00e4nde sind kalt wie die einer Leichenhalle. Eigentlich ist es egal, ob man nackt oder angezogen dorthin geht, man f\u00fchlt sich dort kalt. Man beobachtet den Abschied derer, die ihr Leben mit gro\u0002\u00dfen Zeremonien und gro\u00dfen K\u00e4mpfen verbracht haben.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie werden \u00fcberw\u00e4ltigt von den Eindr\u00fccken, wenn Sie in das Zimmer eines Staatsanwalts gehen, der Ihnen ein Gedichtbuch gibt. Dort k\u00f6nnen Sie ein Gedicht lesen, in dem es um die Augen eines Jun\u0002gen geht, der vergewaltigt wurde, als er vier Jahre alt war. Was w\u00fcrden Sie von Gedichten erwarten, die von einem Staatsanwalt verfasst wur\u0002den? Es spricht B\u00e4nde und dreht sich nur um Schmerz.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie bekommen irgendwann Hunger und gehen in die Kantine. Ihr Essen wird von einem Freund aus Kindertagen serviert, der wegen Armut und Loyalit\u00e4t in einer besch\u00e4mten Weise inhaftiert war, und immer noch Spuren aus dem Gef\u00e4ngnis tr\u00e4gt. Sie verlassen dann das Geb\u00e4ude, um sich eine Zigarette anzuz\u00fcnden, und jemand n\u00e4hert sich, um nach einer zu fragen. Er hat Ihre Brieftasche ge\u0002stohlen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie erkennen, dass es keinen Unterschied gibt, ob Sie Geld stehlen, eine Ehe beenden, jemanden vergewaltigen oder t\u00f6ten. Weil die Leute, die im Gerichtsgeb\u00e4ude landen, auf jeden Fall nicht vollst\u00e4ndig sind. Gerichtsh\u00e4user \u00e4hneln Friedh\u00f6fen, auf denen sich<br>die Verstorbene und ihre Lieben f\u00fcr kurze Zeit treffen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dann beobachten Sie die Verhaftung jener Staatsanw\u00e4lte, die mit Ihnen rund um die Uhr all diesen Schmerz erleben, die um<br>\u201eHoffnung\u201c und \u201eGerechtigkeit\u201c gebeten werden und f\u00fcr Tausende von Tr\u00e4nen arbeiten, nur weil sie dem Befehl \u201eSei ungerecht!\u201d nicht<br>gefolgt sind. Sie beobachten ihre Verhaftung und wissen, dass sie unschuldig sind. Das Gerichtshaus zerf\u00e4llt dann aus diesen Ungerechtigkeiten. Sie k\u00f6nnen nicht vor dem Wrack fliehen und bleiben unter den Tr\u00fcmmern. Ich wei\u00df nicht, was das Konzept des ,,Gerichtsgeb\u00e4udes\u201d in den Gedanken anderer hervorruft, aber es erinnert mich an einen Fried\u0002hof, auf dem ich mich auch begraben habe. Da Politik die Besch\u00e4ftigung f\u00fcr den Narren ist, w\u00fcrden die  Weisen nach Gerechtigkeit suchen, sie fordern und dar\u00fcber sprechen. Aus diesem Grund schrieb ich auf meiner Facebook-Seite: \u201eFolter<br>ist ein Verbrechen, der Staat ist f\u00fcr Gerechtigkeit zust\u00e4ndig und kann kein Verbrechen begehen\u201c, als ich sah, wie Soldaten und Zivilisten in<br>Unterw\u00e4sche nach dem eher zwielichtigen Milit\u00e4r-Putschversuch vom 15. Juli 2016 in St\u00e4llen zusammengeschlagen wurden. Es war die<br>n\u00e4chste Nacht, als sie einen Haft befehl gegen mich ausstellten, weil ich es wagte zu sagen, \u201eFolter ist ein Verbrechen gegen die Mensch\u0002lichkeit\u201c. Der Haft befehl wurde wegen Terrorpropaganda ausgestellt.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe mich nicht gemeldet. Ich lebte wie ein Fl\u00fcchtling mit meiner \u00e4lteren Tochter, die 7 Jahre alt war, und der J\u00fcngeren, die nur sieben<br>Monate alt war. Dann musste ich sie beide verlassen! Weil diese Gerichtsgeb\u00e4ude nicht einmal der Friedhof war, auf dem sich verzweifelte und unvollst\u00e4ndige Menschen versammelten. Sie waren wie ein Kessel, in den Menschen ungeachtet ihrer Schuld oder Unschuld geworfen wurden. Es war ein Kessel, in dem Menschen ver\u0002brannt wurden, um die Wahrheit zu verbergen und die Angst warm und frisch zu halten. Es war ein Kessel, in dem niemand die Schreie der Verbrannten h\u00f6rte!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>W\u00e4hrend meines Berufslebens als Journalistin wurde ich nie wegen gef\u00e4lschter Nachrichten verklagt. Ich wurde nie widerlegt. Vor<br>meinem Haft befehl wurde ich unz\u00e4hlige Male strafrechtlich verfolgt und verklagt. Bei all dem ging es um \u201eOff enlegung von Staatsgeheim\u0002nissen\u201c und \u201eVerletzung der Geheimhaltung\u201c.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der 15. Juli wurde zu einer v\u00f6lligen Zweideutigkeit und zu einem Vorwand, die Gerichtsgeb\u00e4ude in Kessel zu verwandeln, in die die Mei\u0002nungsverschiedenheiten aus allen Lebensbereichen geworfen wurden. Ich habe viele Freunde, die ohne Verbrechen im Gef\u00e4ngnis sind.<br>Ich habe meine Tochter nach drei Jahren gesehen, die ich verlassen musste, als sie 7 Monate alt war. Es dauerte drei Jahre, bis ich mich wie\u0002der mit meinen Kindern vereinte. Es gibt viele andere, die noch warten. Meine \u00e4ltere Tochter Emine, die ich mit 7 Jahren verlassen hatte, wusste, dass ich ihre Mutter war und sie zu ihrer Mutter kam. Aber meine j\u00fcngere, Fatma Zehra, kam vor einem Jahr hierher und erkennt mich immer noch nicht vollst\u00e4ndig als Mutter an. Fatma Zehra hat sich nicht an eine Frau gew\u00f6hnen k\u00f6nnen, die sie nicht kannte, an ein Land, das sie nicht kannte, an ein Haus, in dem sie nie gelebt hatte, und an einen Tisch, an dem sie nie gesessen hatte.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich h\u00f6re Sie fast sagen; Sie ist sehr jung und wird sich an Sie gew\u00f6hnen.<br>Wissen Sie was? Ich habe mal geh\u00f6rt, dass man f\u00fcr jemanden keine Mutter sein kann, wenn es zu sp\u00e4t ist. Sie geht jeden Abend ins Bett und sagt: ,,Wir denken positiv. Vielleicht sehe ich meinen Gro\u00dfvater und meine Mutter (Gro\u00dfmutter) <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c. Sie glaubt immer noch, dass sie wegen des Coronavirus nicht nach Hause fl iegen kann. Sie vermisst ihr Zuhause und die Menschen, die sie als ihre El\u0002tern betrachtet, und sie hat Hoff nungen auf ein Wiedersehen. Aber ich existiere nicht f\u00fcr sie.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe auch nichts, um darauf zu hoff en. Keine Vergangen\u0002heit, keine Sprache, keine Freunde, kein Wissen, kein Geld, keine<br>Identit\u00e4t \u2026. Ich bin voller Nichts. Ich habe oft Geld, Eigentum und Trost abgelehnt, f\u00fcr die Leute ihre Seelen verkaufen. Sie k\u00f6nnen mich also nicht mit den<br>Dingen bedrohen, die ich bereits aufgegeben und nie erwartet hatte.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bin in dem Krieg gestorben, in dem ich daf\u00fcr gek\u00e4mpft habe, dass die Menschen in einem freien und demokratischen Land leben. Die Leute, die im Kessel auf mich gewartet haben, die mich zu Tode steinigen wollen, nur wegen der Anschuldigungen der Re\u0002gierung. Die Leute, die nichts \u00fcber mich wissen! Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die To\u0002ten vor nichts Angst haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer ist Arzu Y\u0131ld\u0131z?<br>Arzu Y\u0131ld\u0131z hat in unterschiedlichen Medien wie ; Bir TV (32. G\u00fcn), Star TV, Medya Kronik, Taraf Daily, Haberdar, T24 und Grihat als unabh\u00e4ngige Journalistin gearbeitet. Unmittelbar nach dem Putsch\u0002versuch vom 15. Juli 2016 wurde gegen sie ein Haftbefehl erlassen, weil sie \u201eFolter ist ein Verbrechen, der Staat ist f\u00fcr die Justiz zust\u00e4ndig und kann kein Verbrechen begehen, und Folter ist ein Verbrechen gegen die Menschlichkeit\u201c auf Social Media-Kan\u00e4len postete. Sie lebte vier Monate lang im Untergrund, bevor sie nach Griechenland fl oh und blieb in Fl\u00fcchtlingslagern. Y\u0131ld\u0131z fl og im November 2016 nach Kana\u0002da und beantragte Asyl. Sie wurde nach zwei Jahren mit ihrer \u00e4lteren Tochter und nach drei Jahren mit der j\u00fcngeren Tochter wiederverei\u0002nigt.<br>Sie lieferte Pizza in Kanada und arbeitete in Fabriken und Res\u0002taurants. Derzeit liefert sie Lebensmittel und macht ehrenamtlichen Journalismus bei Gazete Davul. Nachdem Y\u0131ld\u0131z 4 B\u00fccher verfasst hatte, hielt sie eine Rede auf einer Konferenz, die von der Menschenrechtskommission des kana\u0002dischen Parlaments und der Canadian Association of Journalists or\u0002ganisiert wurde. Derzeit ist sie Mitglied der Canadian Asssociation of Journalists, des PEN Canada und der Association of Writers in Exile. Sie ist auch an einem Dokumentarfi lmprojekt mit James Culling\u0002ham, einem Wissenschaftler und Autor f\u00fcr \u201eMeinungsfreiheit\u201c und \u201eFl\u00fcchtlingsjournalisten\u201c, beteiligt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eDie Leute, die im Kessel auf mich gewartet haben, die mich zu Tode steinigen wollten, nur wegen der Anschuldi\u0002gungen der Regierung. Die Leute, die nichts \u00fcber mich wissen! Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben.\u201c ARZU YILDIZ EXILJOURNALISTIN \/ KANADA Ich bin seit 2003 eine unabh\u00e4ngige Journalistin. [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":21752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676],"tags":[5487,4694,5969],"class_list":["post-21750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","tag-arzu-yildiz-2","tag-international-journalists-association","tag-jounalist-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists\" \/>\n<meta property=\"og:description\" content=\"\u201eDie Leute, die im Kessel auf mich gewartet haben, die mich zu Tode steinigen wollten, nur wegen der Anschuldi\u0002gungen der Regierung. Die Leute, die nichts \u00fcber mich wissen! Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben.\u201c ARZU YILDIZ EXILJOURNALISTIN \/ KANADA Ich bin seit 2003 eine unabh\u00e4ngige Journalistin. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-08T11:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-08T11:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben\",\"datePublished\":\"2021-12-08T11:50:45+00:00\",\"dateModified\":\"2021-12-08T11:50:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/\"},\"wordCount\":1424,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Arzu_Yildiz_jp1_DE.jpg\",\"keywords\":[\"Arzu Y\u0131ld\u0131z\",\"International Journalists Association\",\"Jounalist Post\"],\"articleSection\":[\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/\",\"name\":\"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Arzu_Yildiz_jp1_DE.jpg\",\"datePublished\":\"2021-12-08T11:50:45+00:00\",\"dateModified\":\"2021-12-08T11:50:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Arzu_Yildiz_jp1_DE.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Arzu_Yildiz_jp1_DE.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/","og_locale":"de_DE","og_type":"article","og_title":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists","og_description":"\u201eDie Leute, die im Kessel auf mich gewartet haben, die mich zu Tode steinigen wollten, nur wegen der Anschuldi\u0002gungen der Regierung. Die Leute, die nichts \u00fcber mich wissen! Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben.\u201c ARZU YILDIZ EXILJOURNALISTIN \/ KANADA Ich bin seit 2003 eine unabh\u00e4ngige Journalistin. [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-08T11:50:45+00:00","article_modified_time":"2021-12-08T11:50:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben","datePublished":"2021-12-08T11:50:45+00:00","dateModified":"2021-12-08T11:50:47+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/"},"wordCount":1424,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg","keywords":["Arzu Y\u0131ld\u0131z","International Journalists Association","Jounalist Post"],"articleSection":["Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/","url":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/","name":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg","datePublished":"2021-12-08T11:50:45+00:00","dateModified":"2021-12-08T11:50:47+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Arzu_Yildiz_jp1_DE.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/es-gibt-nichts-mehr-was-mich-erschrecken-koennte-weil-die-toten-vor-nichts-angst-haben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Es gibt nichts mehr, was mich erschrecken k\u00f6nnte, weil die Toten vor nichts Angst haben"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=21750"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/21752"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=21750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=21750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=21750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}