{"id":21742,"date":"2021-12-08T12:38:54","date_gmt":"2021-12-08T11:38:54","guid":{"rendered":"https:\/\/ijaev.org\/?p=21742"},"modified":"2021-12-08T12:38:56","modified_gmt":"2021-12-08T11:38:56","slug":"baelle-die-in-den-hof-fallen","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/","title":{"rendered":"B\u00e4lle, die in den Hof fallen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201eIch war mit dem Jorunalisten Ziya Ataman gemeinsam im<br>Hochsicherheitsgef\u00e4ngnis von Van inhaft iert. Wir haben aus ver\u0002dorbenem Brot und Zeitungspapier B\u00e4lle gebastelt und darin Zettel<br>mit Notizen reingetan. Dann haben wir die Zellennummer drauf\u0002geschrieben und sie von Hof zu Hof geworfen. Das war unsere<br>Art miteinander zu kommunizieren.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0130dris Y\u0131lmaz \/ FREIER JOURNALIST<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Journalist Ziya Ataman geh\u00f6rt zu den Journalisten, die in der T\u00fcrkei Opfer der seit Jahren anhaltenden Ein\u0002sch\u00fcchterungs- und Unterdr\u00fcckungspolitik gegen den kurdischen Journalismus geworden sind. Ataman sollte zum Schweigen gebracht werden und gehorchen. Deswegen wur\u0002de der Journalist am 11. April 2016 in Van festgenommen. Seit \u00fcber 4 Jahren ist der Journalist hinter Gittern und wartet dort auf seine Freiheit. Das ist die Geschichte von Ziya Ataman\u2026 Ziya Ataman hat als Journalist zuerst in den Zeitungen \u201eAzadiye Welat\u201c und \u201e\u00d6zg\u00fcr G\u00fcndem\u201c gearbeitet. Zun\u00e4chst aber arbeitete er als Zeitungsverteiler. Wegen der Unterr\u00fc\u0002ckung durch die Sicherheitsbeh\u00f6rden ging er dann sp\u00e4ter dann zun\u00e4chst nach Diyarbak\u0131r und dann nach Van. Dort wurde er festgenommen, als er f\u00fcr die Nachrichtenagentur \u201eDicleHa\u0002ber Ajans\u0131\u201c DIHA arbeitete. Einen Tag nach seiner Festnahme wurde ihm Mitgliedschaft in einer Terrororganisation vorge\u0002worfen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zeugen sagten unter Folter aus Als Beweismittel gab es nur einige Zeugenaussagen. Diese Personen hatten sp\u00e4ter beteuert ihre Aussagen unter Folter ge\u0002macht zu haben und zogen deswegen Aussagen zur\u00fcck. Damit wurde das einzige Beweismittel der Staatsanwaltschaft un\u0002brauchbar. Das hat aber nichts ge\u00e4ndert. Ataman wurde den\u0002noch nicht freigelassen. Erst 20 Monate nach seiner Festnahme wurde die Anklageschrift f\u00fcr den Journalisten im Dezember<br>2017 fertiggestellt.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Richtige Verteidigung nicht m\u00f6glich Ataman konnte an seiner Gerichtsverhandlung \u00fcber das Videokonferenzsystem SEGBIS von seinem Gef\u00e4ngnis aus teil\u0002nehmen. Wegen technischer Probleme konnte er sich nicht richtig verteidigen. Er konnte nur einige Minuten sprechen. Damit die Unschuld des Journalisten nicht bewiesen werden konnte, wurden die Umst\u00e4nde erschwert und es wurde schwe\u0002rer psychischer Druck auf den Journalisten ausge\u00fcbt.<br>14 Jahre und 3 Monate Gef\u00e4ngnis Das Urteil wurde am 24. September 2019 gef\u00e4llt. Seine Kol\u0002legen und Verteidiget erwarteten einen Freispruch. Das ist aber<br>nicht passiert. Ohne konkrete Beweise wurde der Journalist Ziya Ataman am Ende zu 14 Jahren und 3 Monaten Gef\u00e4ngnis verurteilt.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Angeschlagener Gesundheitszustand Seit \u00fcber vier Jahren ist Ataman jetzt im Gef\u00e4ngnis und k\u00e4mpft mit gesundheitlichen Problemen im Darmberich.<br>W\u00e4hrend der Haftzeit hat sich sein Gesundheitszustand weiter verschlechtert. Und eine Therapie ist momentan sehr schwierig.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kein faires Gerichtsverfahren W\u00e4hrend der gesamten Haftzeit von Ataman wurden wir Zeugen, wie auch die Rechte anderer Journalisten, Politiker<br>und Intellektueller mit den F\u00fc\u00dfen getreten wurden. In den Gerichtsprozessen sehen wir, wie die Europ\u00e4ische Menschen\u0002rechtskonvention verletzt wird. \u201eJede Person hat ein Recht darauf, dass \u00fcber Streitigkeiten in Bezug auf ihre zivilrechtli\u0002chen Anspr\u00fcche und Verpflichtungen oder \u00fcber eine gegen sie<br>erhobene strafrechtliche Anklage von einem unabh\u00e4ngigen und unparteiischen, auf Gesetz beruhenden Gericht in einem fairen Verfahren, \u00f6ffentlich und innerhalb angemessener Frist verhandelt wird.\u201c Mit dem ersten Satz von Artikel 6 der Kon\u0002vention wird damit jedem ein faires Verfahren garantiert, die<br>vielen verwehrt bleibt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Unterschriftenkampagne<br>Damit Ataman aus dem Gef\u00e4ngnis entlassen wird, wurde eine Unterschriftenkampagne auf cahnge.org organisiert. Sein Kollege Selman Kele\u015f hat diese Aktion ins Leben gerufen, um darauf aufmerksam zu machen, dass \u201eAtaman unschuldig ist, er keine ausreichende medizinische Versorgung im Gef\u00e4ngnis<br>bekommt und er keinen faires Gerichtsverfahren\u201c hatte.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eJahre sp\u00e4ter im Gef\u00e4ngnis getroffen\u201c<br>Ich bin seit Jahren mit Ziya befreundet. Es war im Januar 2016. Ich sa\u00df wegen meiner Artikel im Gef\u00e4ngnis und sollte wieder entlassen werden. Es war damals sehr kalt. Mein K\u00f6r\u0002per, der zwischen Betonw\u00e4nde eingesperrt war, hatte erstmals wieder Kontakt mit hochkonzentrierter Frischluft. Als die kalte Luft mein Gesicht ber\u00fchrte hatte, zitterten meine Bei\u0002ne und K\u00f6rper. Ein Gruppe von Journalisten, unter ihnen auch Ziya, hatte mich empfangen. Das war unser erster Kontakt. Wir hatten uns umarmt, als w\u00e4ren wir seit jahrzehnten Freunde. Diese Freundschaft wurde immer st\u00e4rker. Sp\u00e4ter wurde unsere Freundschaft getrennt, weil wir beide erneut ins Gef\u00e4ngnis ka\u0002men. Jahre sp\u00e4ter begegneten wir uns wieder im Hochsicher\u0002heitsgef\u00e4ngnis von Van.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Bedingungen im Gef\u00e4ngnis sind gnadenlos. In dem kleinen Hof darf es nicht einmal eine kleine Pflanze geben. Die Gef\u00e4ngnisw\u00e4rter haben nach ihrer morgendlichen Z\u00e4hlung ihr Augenmerk in die Ecken des Hofes gerichtet. Pflanzen und Insekten, mit denen man sich unterhalten konnte, wurden so\u0002fort entfernt. Trotz der schwierigen Bedingungen hatten wir dennoch Gespr\u00e4che mit Ziya nach der Nachtz\u00e4hlung. Es waren keine herk\u00f6mmlichen Gespr\u00e4che. Wir haben uns schriftli\u0002chunterhalten.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B\u00e4lle, die in den Hof fallen<br>Wir bauten uns B\u00e4lle aus Zeitung und verdorbenem Brot. Darin haben wir unsere Nachrichten reingetan, die Zellen\u0002nummer draufgeschrieben und soweit es ging in die anderen H\u00f6fe geworfen. Das war unser Kommunikationsweg. Damit die Aufseher nicht unsere Botschaftszettel in die H\u00e4nde beka\u0002men, haben wir diese B\u00e4lle nach der n\u00e4chtlichen Z\u00e4hlung uns gegenseitig zugeworfen. Wir haben uns danach starken Tee gemacht und dabei diese Zettel gelesen und beantwortet. Die Stille in der Zelle fand dadurch ein Ende. Wir hatten uns bei ei\u0002nem solchen \u201eGespr\u00e4ch\u201c erneut getroffen. Ich und Ziya haben die W\u00f6rter sehr klein geschrieben. Wir haben uns dar\u00fcber ge\u0002schrieben, was in unserem Inneren geschieht. Ziya hatte \u00fcber seine Tr\u00e4ume geschrieben, was er tun w\u00fcrde, wenn er wieder in Freiheit k\u00e4me. Ziya hatte das ungerechte Rechtssystem kri\u0002tisiert, dass ihn ins Gef\u00e4ngnis warf. Er hatte seine Botschaften<br>mit \u201eGuten Tag Heval Idris, wo waren wir in unserem Gespr\u00e4ch nochmal stehen geblieben,\u201c angefangen. Ich konnte seine Be\u0002schwerden in seinen Botschaften sp\u00fcren. Es sind jetzt mehr als 1.600 Tage vergangen, dass Ziya ins Gef\u00e4ngnis geworfen wurde.<br>Ich vermisse ihn sehr. Ich w\u00fcnsche mir sehr, dass er schnellst\u0002m\u00f6glich wieder in Freiheit kommt.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Diesen Text hat der Journalist \u0130dris Y\u0131lmaz geschrieben. Er verbrachte<br>21 Monate im Gef\u00e4ngnis von Elaz\u0131\u011f und wurde zu 6 Jahren und 3 Monaten<br>Gef\u00e4ngnis verurteilt. Das Verfahren befindet sich in Berufung. Sollte d<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u201eIch war mit dem Jorunalisten Ziya Ataman gemeinsam imHochsicherheitsgef\u00e4ngnis von Van inhaft iert. Wir haben aus ver\u0002dorbenem Brot und Zeitungspapier B\u00e4lle gebastelt und darin Zettelmit Notizen reingetan. Dann haben wir die Zellennummer drauf\u0002geschrieben und sie von Hof zu Hof geworfen. Das war unsereArt miteinander zu kommunizieren.\u201c \u0130dris Y\u0131lmaz \/ FREIER JOURNALIST Der Journalist Ziya Ataman [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":21743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676],"tags":[5968,4694,5969],"class_list":["post-21742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","tag-idris-yilmaz-2","tag-international-journalists-association","tag-jounalist-post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00e4lle, die in den Hof fallen - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e4lle, die in den Hof fallen - International Journalists\" \/>\n<meta property=\"og:description\" content=\"\u201eIch war mit dem Jorunalisten Ziya Ataman gemeinsam imHochsicherheitsgef\u00e4ngnis von Van inhaft iert. Wir haben aus ver\u0002dorbenem Brot und Zeitungspapier B\u00e4lle gebastelt und darin Zettelmit Notizen reingetan. Dann haben wir die Zellennummer drauf\u0002geschrieben und sie von Hof zu Hof geworfen. Das war unsereArt miteinander zu kommunizieren.\u201c \u0130dris Y\u0131lmaz \/ FREIER JOURNALIST Der Journalist Ziya Ataman [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-08T11:38:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-08T11:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"B\u00e4lle, die in den Hof fallen\",\"datePublished\":\"2021-12-08T11:38:54+00:00\",\"dateModified\":\"2021-12-08T11:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/\"},\"wordCount\":1024,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Idris_Yilmaz_jp1_DE.jpg\",\"keywords\":[\"\u0130dris Y\u0131lmaz\",\"International Journalists Association\",\"Jounalist Post\"],\"articleSection\":[\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/\",\"name\":\"B\u00e4lle, die in den Hof fallen - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Idris_Yilmaz_jp1_DE.jpg\",\"datePublished\":\"2021-12-08T11:38:54+00:00\",\"dateModified\":\"2021-12-08T11:38:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Idris_Yilmaz_jp1_DE.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Idris_Yilmaz_jp1_DE.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/baelle-die-in-den-hof-fallen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00e4lle, die in den Hof fallen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00e4lle, die in den Hof fallen - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/","og_locale":"de_DE","og_type":"article","og_title":"B\u00e4lle, die in den Hof fallen - International Journalists","og_description":"\u201eIch war mit dem Jorunalisten Ziya Ataman gemeinsam imHochsicherheitsgef\u00e4ngnis von Van inhaft iert. Wir haben aus ver\u0002dorbenem Brot und Zeitungspapier B\u00e4lle gebastelt und darin Zettelmit Notizen reingetan. Dann haben wir die Zellennummer drauf\u0002geschrieben und sie von Hof zu Hof geworfen. Das war unsereArt miteinander zu kommunizieren.\u201c \u0130dris Y\u0131lmaz \/ FREIER JOURNALIST Der Journalist Ziya Ataman [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-08T11:38:54+00:00","article_modified_time":"2021-12-08T11:38:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"B\u00e4lle, die in den Hof fallen","datePublished":"2021-12-08T11:38:54+00:00","dateModified":"2021-12-08T11:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/"},"wordCount":1024,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg","keywords":["\u0130dris Y\u0131lmaz","International Journalists Association","Jounalist Post"],"articleSection":["Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/","url":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/","name":"B\u00e4lle, die in den Hof fallen - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg","datePublished":"2021-12-08T11:38:54+00:00","dateModified":"2021-12-08T11:38:56+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Idris_Yilmaz_jp1_DE.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/baelle-die-in-den-hof-fallen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"B\u00e4lle, die in den Hof fallen"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=21742"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/21743"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=21742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=21742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=21742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}