{"id":21592,"date":"2021-12-07T09:23:54","date_gmt":"2021-12-07T08:23:54","guid":{"rendered":"https:\/\/ijaev.org\/?p=21592"},"modified":"2021-12-07T15:49:29","modified_gmt":"2021-12-07T14:49:29","slug":"gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/","title":{"rendered":"Gibt es eigentlich ein Mahnmal der Pressefreiheit?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201eAls fast 40 t\u00fcrkische Journalisten im Hochsicherheitsgef\u00e4ngnis Silivri im Mai 2020 von Corona bedroht waren, haben wir in kurzer Zeit alle Betroffenen portraitiert und ihre Portraits als Offenen Brief mit \u00fcber 100 Unterzeichnerinnen u.a. an Pr\u00e4sident Erdogan geschickt.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gibt es eigentlich ein Mahnmal der Pressefreiheit? Ja, das gibt es, und zwar online. Auf www.wahrheitskaemp\u0002fer.de haben K\u00fcnstlerInnen Portraits von ermordeten, inhaftierten und verfolgten JournalistInnen gemalt und ge\u0002zeichnet. Entstanden ist eine eindrucksvolle Sammlung ganz unterschiedlicher Portraits. Unter dem Motto REMEMBER THEIR FACES &#8211; REMEMBER THEIR STORIES k\u00f6nnen die Besu\u0002cherInnen dieser Online-Gedenkst\u00e4tte \u00fcber 300 mutigen Hel\u0002dInnen der Pressefreiheit begegnen &#8211; und unsere Sammlung w\u00e4chst st\u00e4ndig weiter. Denn WAHRHEITSK\u00c4MPFER ist ein of\u0002fenes Projekt, dem sich weltweit schon 35 K\u00fcnstlerInnen ange\u0002schlossen haben. Und es werden immer mehr. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es sind die Schandtaten der M\u00e4chtigen, die die Journalis\u0002tInnen aufgedeckt hatten. M\u00e4chtige Politiker, m\u00e4chtige Polizei\u0002beamte, m\u00e4chtige Drogenbanden, m\u00e4chtige Industrielle haben sich nicht an Gesetze gehalten, haben die Natur gepl\u00fcndert und zerst\u00f6rt, haben vergewaltigt, gestohlen oder sich bestechen las\u0002sen. Dar\u00fcber berichteten die JournalistInnen, bevor sie einge\u0002sch\u00fcchtert, bedroht, verhaftet, gefoltert und ermordet wurden. Von gerade diesen Leuten. Die bleiben meistens straffrei. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emp\u00f6rung, Wut und Ohnmacht \u2013 doch diesen negativen Gef\u00fchlen setzen wir etwas Positives entgegen: Dankbarkeit und Bewunderung f\u00fcr den Mut dieser JournalistInnen. Es ist sch\u00f6n zu sehen, wieviel Entschlossenheit und Neugier aus ih\u0002ren Gesichtern spricht, und es ist jedes Mal ber\u00fchrend f\u00fcr uns, ihnen diese Ehre zu erweisen, sie zu zeichnen und sie In unserer Sammlung zu vereinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir zeigen Teile dieser Sammlung auch physisch in ei\u0002ner Wanderausstellung auf der ganzen Welt und arbeiten u.a. mit Reporter ohne Grenzen, Amnesty International und der UNESCO zusammen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als fast 40 t\u00fcrkische Journalisten im Hochsicherheits\u0002gef\u00e4ngnis Silivri im Mai 2020 von Corona bedroht waren, ha\u0002ben wir in kurzer Zeit alle Betroffenen portraitiert und ihre Portraits als Offenen Brief mit \u00fcber 100 Unterzeichnerinnen u.a. an Pr\u00e4sident Erdogan geschickt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>In den Schaufenstern von Buchhandlungen, Kunstga\u0002lerien und Kinos warben wir f\u00fcr weitere UnterzeichnerIn\u0002nen. Eine Antwort von Erdogan? Fehlanzeige. Das macht aber nichts. Weitermachen! Im Jemen sind 4 mutige Journalisten von der Todesstrafe bedroht, in Lukaschenkos Belarus gra\u0002ben wir alte F\u00e4lle von Morden an JournalistInnen aus und zeichnen bewundernswert mutige aktive belarussische Jour\u0002nalistInnen der Gegenwart. Unser neuester Fall ist der Mord<br>an dem mexikanischen Journalisten Julio Valdivia. Er wur\u0002de enthauptet, doch es sollte wie ein Motoradunfall auf den Bahngleisen aussehen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte Sie alle einladen, unser Projekt im Internet zu besuchen. Vielleicht kennen Sie F\u00e4lle, die noch fehlen und k\u00f6nnen uns Informationen zukommen lassen. Vielleicht kennen Sie K\u00fcnstlerInnen, die gerne Portraits zeichnen? Oder w\u00fcrden Sie gerne selbst recherchieren und Texte verfassen? Unterst\u00fctzen Sie dieses Projekt! Unser gemeinn\u00fctziger Ver\u0002ein Wahrheitsk\u00e4mpfer e.V. freut sich auch \u00fcber Spenden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eAls fast 40 t\u00fcrkische Journalisten im Hochsicherheitsgef\u00e4ngnis Silivri im Mai 2020 von Corona bedroht waren, haben wir in kurzer Zeit alle Betroffenen portraitiert und ihre Portraits als Offenen Brief mit \u00fcber 100 Unterzeichnerinnen u.a. an Pr\u00e4sident Erdogan geschickt.\u201c Gibt es eigentlich ein Mahnmal der Pressefreiheit? Ja, das gibt es, und zwar online. Auf www.wahrheitskaemp\u0002fer.de haben [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":21593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[4676],"tags":[3092,5496,4721,5501],"class_list":["post-21592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-author","tag-international-journalists-en-de","tag-journalist-post-2","tag-pressefreiheit-2","tag-susanne-koehler"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists\" \/>\n<meta property=\"og:description\" content=\"\u201eAls fast 40 t\u00fcrkische Journalisten im Hochsicherheitsgef\u00e4ngnis Silivri im Mai 2020 von Corona bedroht waren, haben wir in kurzer Zeit alle Betroffenen portraitiert und ihre Portraits als Offenen Brief mit \u00fcber 100 Unterzeichnerinnen u.a. an Pr\u00e4sident Erdogan geschickt.\u201c Gibt es eigentlich ein Mahnmal der Pressefreiheit? Ja, das gibt es, und zwar online. Auf www.wahrheitskaemp\u0002fer.de haben [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T08:23:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-07T14:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Gibt es eigentlich ein Mahnmal der Pressefreiheit?\",\"datePublished\":\"2021-12-07T08:23:54+00:00\",\"dateModified\":\"2021-12-07T14:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Susanne-Kohler_jp1_DE.jpg\",\"keywords\":[\"International Journalists\",\"Journalist Post\",\"Pressefreiheit\",\"Susanne K\u00f6hler\"],\"articleSection\":[\"Authoren\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/\",\"name\":\"Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Susanne-Kohler_jp1_DE.jpg\",\"datePublished\":\"2021-12-07T08:23:54+00:00\",\"dateModified\":\"2021-12-07T14:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Susanne-Kohler_jp1_DE.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Susanne-Kohler_jp1_DE.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gibt es eigentlich ein Mahnmal der Pressefreiheit?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/","og_locale":"de_DE","og_type":"article","og_title":"Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists","og_description":"\u201eAls fast 40 t\u00fcrkische Journalisten im Hochsicherheitsgef\u00e4ngnis Silivri im Mai 2020 von Corona bedroht waren, haben wir in kurzer Zeit alle Betroffenen portraitiert und ihre Portraits als Offenen Brief mit \u00fcber 100 Unterzeichnerinnen u.a. an Pr\u00e4sident Erdogan geschickt.\u201c Gibt es eigentlich ein Mahnmal der Pressefreiheit? Ja, das gibt es, und zwar online. Auf www.wahrheitskaemp\u0002fer.de haben [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2021-12-07T08:23:54+00:00","article_modified_time":"2021-12-07T14:49:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Gibt es eigentlich ein Mahnmal der Pressefreiheit?","datePublished":"2021-12-07T08:23:54+00:00","dateModified":"2021-12-07T14:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/"},"wordCount":498,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg","keywords":["International Journalists","Journalist Post","Pressefreiheit","Susanne K\u00f6hler"],"articleSection":["Authoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/","url":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/","name":"Gibt es eigentlich ein Mahnmal der Pressefreiheit? - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg","datePublished":"2021-12-07T08:23:54+00:00","dateModified":"2021-12-07T14:49:29+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2021\/12\/Susanne-Kohler_jp1_DE.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/gibt-es-eigentlich-ein-mahnmal-der-pressefreiheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Gibt es eigentlich ein Mahnmal der Pressefreiheit?"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=21592"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/21592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/21593"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=21592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=21592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=21592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}