{"id":18652,"date":"2020-10-22T21:04:33","date_gmt":"2020-10-22T19:04:33","guid":{"rendered":"http:\/\/internationaljournalists.org\/?p=18652"},"modified":"2020-10-22T21:04:40","modified_gmt":"2020-10-22T19:04:40","slug":"mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/","title":{"rendered":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die Frankfurter Rundschau feiert ihren 75. Geburtstag und macht zu diesem Anlass eine Liste 75 beeindruckender Pers\u00f6nlichkeiten unserer Zeitgeschichte bekannt. Mit seinem unerm\u00fcdlichen Einsatz f\u00fcr Demokratie und Menschenrechte in der T\u00fcrkei hat es der seit mehr als vier Jahren mit einer kleinen Unterbrechung inhaftierte Intellektuelle und Journalist Ahmet Altan auch auf diese Liste geschafft.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit dem 9. September ist der heute 70-j\u00e4hrige Familienvater in Haft. Er wurde im Februar 2018 wegen angeblicher Verbindungen zur G\u00fclen-Bewegung zun\u00e4chst zu lebenslanger Haft verurteilt. Inzwischen wurde die Strafe auf zehneinhalb Jahre reduziert.&nbsp;<a href=\"https:\/\/dtj-online.de\/putsch-in-der-tuerkei-journalisten-verurteilt-und-freigelassen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ein t\u00fcrkisches Gericht hatte&nbsp;Altan&nbsp;im November 2019 nach drei Jahren Untersuchungshaft unter Auflagen wieder freigelassen.<\/a>&nbsp;Wenige Tage sp\u00e4ter wurde er jedoch erneut verhaftet. Experten vermuten, hinter seiner erneuten Verhaftung liegt sein erster und soweit einziger Artikel nach der Haft, \u201e<a href=\"https:\/\/dtj-online.de\/papierfloete-ahmet-altan-verhaftung-tuerkei\/\">Die Papierfl\u00f6te<\/a>\u201c. Nach dem n\u00e4chsten Absatz k\u00f6nnen Sie den besagten Beitrag lesen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ahmet Altan und Nelson Mandela auf der Liste der Frankfurter Rundschau<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gestern wurde der immer noch inhaftierte Altan mit der Auflistung in der Frankfurter Rundschau honoriert. Eine weitere internationale Auszeichnung, die Altan nicht pers\u00f6nlich entgegennehmen kann. Vermutlich wird ihn diese Nachricht sogar mehrere Tage sp\u00e4ter erreichen. Vielleicht sogar dann, wenn diese Nachricht inmitten der Aktualit\u00e4t aus dem Ged\u00e4chtnis vieler Menschen in Freiheit wieder verschwunden ist. Die Zeitung macht aber mit dieser W\u00fcrdigung auf Altan aufmerksam \u2013 als einer der 75 Menschen, die der gesamten Welt Mut machen. In dieser Liste sind neben Altan auch Namen wie Nelson Mandela zu finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">***<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Die Macht in den H\u00e4nden eines Ungerechten<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Schlimmste auf der Welt ist es, der grauenvollen Macht eines Menschen zu begegnen, der \u00fcber dein Schicksal verf\u00fcgt. Diese Person kann dich t\u00f6ten, dich einsperren, ins Exil schicken oder freilassen. Ungeachtet der unterschiedlichen Folgen ist es ebenso zerm\u00fcrbend, von einer solchen Person eingesperrt oder freigelassen zu werden. Denn du hast gar kein Mitspracherecht. Menschen mit solch einer Autorit\u00e4t tragen in der Regel eine Robe und sitzen auf einer hohen Kanzel. Sie werden Richter genannt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das einzige Verzeihliche daran, einem Menschen eine so \u00fcbermenschliche Macht zu verleihen, ist es, wenn diese Macht gerecht Anwendung findet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und was passiert, wenn dies nicht der Fall ist und diese Macht missbraucht wird?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ahmet Altan zitiert Ernest Hemingway<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In einer Szene aus dem Buch \u201eIn einem andern Land\u201c von Ernest Hemingway werden in einer Zeit, in der die Italiener eine Niederlage erleiden, Soldaten in einer H\u00f6hle durch Milit\u00e4rrichter zu Tode verurteilt. In einer unantastbaren Manier, als w\u00fcrden ihre Entscheidungen niemals auf sie zur\u00fcckfallen, setzen sie bei jeder Entscheidung ihre Kappen auf, salutieren und schicken die Menschen in den Tod. Auch in dem Film, in dem Rock Hudson und Vittorio de Sica spielen, ist diese Szene einmalig. Sie f\u00e4llen ihre Urteile und schicken die Menschen in den Tod.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In meiner langen Haftzeit wurde ich mehrmals einem Richter vorgef\u00fchrt. Sie haben mir nicht einmal zugeh\u00f6rt. Ganz gleich, welche Belege ich f\u00fcr meine Unschuld anf\u00fchrte, behandelten sie mich wie Luft und wiederholt blo\u00df die bereits erhobenen Vorw\u00fcrfe gebetsm\u00fchlenartig. Zun\u00e4chst wurde ich lebensl\u00e4nglich verurteilt. Danach wurde die Strafe auf zehneinhalb Jahre verk\u00fcrzt und schlie\u00dflich lie\u00dfen sie mich frei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich schreibe dies, w\u00e4hrend ich auf die Berufung eines Staatsanwalts bez\u00fcglich meiner Freilassung und die Entscheidung eines Richters warte; ich k\u00f6nnte zur\u00fcck ins Gef\u00e4ngnis gehen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lebenslange Haft und Freilassung vom selben Richter<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Urteile zu lebenslanger Haft und meiner Freilassung h\u00f6rte ich zu verschiedenen Zeitpunkten aus dem Mund desselben Richters. Die Freilassung hat mich genauso sehr bedr\u00fcckt wie meine Verurteilung zu lebenslanger Haft. Denn derjenige, der \u00fcber mich entschieden hatte, war jemand, der diese Befugnisse nicht h\u00e4tte haben d\u00fcrfen. Das war mir bewusst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe das Gef\u00e4ngnis verlassen, aber Tausende unschuldige Menschen sind immer noch drinnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u201eDschungel aus dicken W\u00e4nden und Stahlt\u00fcren\u201c<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Als ich aus diesem Dschungel aus dicken W\u00e4nden und Stahlt\u00fcren schritt, lie\u00df ich verzweifelte Menschen hinter mir zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich lebte \u00fcber drei Jahre in einer kleinen Zelle mit zwei anderen Insassen, die keine Verbrechen begangen hatten. Niemand hat ihnen zugeh\u00f6rt, und obwohl sie mehrmals beteuerten, unschuldig zu sein, wurden sie von Richtern, die jenen im Roman \u201eIn einem andern Land\u201c \u00e4hnelten, verurteilt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Altan \u00fcber Mitinsassen: \u201eWie mein Sohn\u201c<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Einer von ihnen ist im selben Alter wie mein Sohn. Er war frisch verheiratet, als sie ihn verhafteten. Eine tief religi\u00f6se Person, aber zugleich auch an Philosophie und Wissenschaft interessiert. Er ist handwerklich erstaunlich geschickt, aus den unterschiedlichsten und eigentlich nicht in Frage kommenden Materialien machte er verbl\u00fcffende Sachen.&nbsp;Aus Salzverpackungen Hanteln, aus Gabeln W\u00e4scheklammern und aus Teel\u00f6ffeln Pinzetten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch das Zuf\u00fchren von diversen Zutaten in Gef\u00e4ngnismahlzeiten konnte er ganz neue Gerichte kreieren. Sein Name ist Selman. Er glaubt, sich zu beschweren sei Auflehnung gegen\u00fcber das von Gott bestimmte Schicksal. Drum beschwerte er sich nie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aus unterschiedlichen Gr\u00fcnden hatte er nie Besuch.&nbsp;Auch dar\u00fcber beschwerte er sich nicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Die nette \u00dcberraschung im Gef\u00e4ngnis<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Als ich eines Tages auf dem Plastiktisch meinen neuen Roman schrieb, h\u00f6rte ich im Hof \u200b\u200bMusik. Es war der Klang einer Fl\u00f6te. Ich ging auf den Hof. Selman hatte den R\u00fccken an die Wand gelehnt, die Augen geschlossen und spielte Fl\u00f6te. Die Ger\u00e4usche in und aus den umliegenden Zellen lie\u00dfen nach. Jeder lauschte dieser unerwarteten Melodie. Als Selmans St\u00fcck vorbei war, gab es ein lautes Klappern aus allen Zellen. In der Gef\u00e4ngniskantine gekaufte Bonbons wurden in unseren Hof geworfen und so um Zugabe gebeten. Selman spielte stundenlang.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nachdem wir wieder in der Halle waren, fragte ich ihn, wo er diese Fl\u00f6te gefunden hatte. Er hatte es mit den Pappseiten eines Kalenders gebastelt. Da er kein Ma\u00dfband hatte, musste er den Abstand zwischen den einzelnen L\u00f6chern sch\u00e4tzen. Er drehte den Deckel einer Plastikflasche in das Mundst\u00fcck.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Altan \u00fcber die Papierfl\u00f6te von Selman<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kein anderes Instrument auf der Erde konnte mit dem Klang dieser Fl\u00f6te mithalten. Es hatte einen seltsam wehm\u00fctigen und etwas tiefen Ton. Selman hat nie eine Note verpasst. Er spielte nicht nur traurige St\u00fccke, sondern auch Fr\u00f6hliches, aber immer wieder glitt der Klang seiner Fl\u00f6te ins Melancholische.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er war wie mein Sohn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kein Angeh\u00f6riger kam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht einmal hat er sich beklagt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er hat sich eine Papierfl\u00f6te gebastelt, sich an die Wand gelehnt und darauf gespielt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als ich eines Nachts pl\u00f6tzlich aus dem Gef\u00e4ngnis entlassen wurde, fragte man mich, wie es mir geht. Sie wollten die Freude eines nach Jahren freigelassenen H\u00e4ftlings h\u00f6ren und sehen. Ich sagte aber, dass ich etwas traurig bin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denn ich hatte Tausende unschuldige Menschen zur\u00fcckgelassen, einschlie\u00dflich Selman. Ich wusste, dass sie unschuldig sind, doch mir fehlte die Kraft, sie zu retten. Und niemand h\u00f6rte ihnen zu. Nicht nur die Richter, sondern ein wirklich gro\u00dfer Teil der Gesellschaft hatte sich in diese ignoranten M\u00e4nner aus \u201eIn einem andern Land\u201c verwandelt und zugeschaut, wie diese M\u00e4nner zu Tode verurteilt wurden. Sie setzen ihre Kappen auf, salutieren, stellen eine Person zur Hinrichtung an die Wand und widmen sich sofort dem n\u00e4chsten Opfer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Als Gefangener Opfer, als Freier ein Komplize<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sobald man diese H\u00f6hle einmal gesehen hat, Zeuge des Leidens unschuldiger Menschen geworden ist und den T\u00f6nen der Papierfl\u00f6te gelauscht hat, ist es nur schwer m\u00f6glich, sich \u00fcber seine Freilassung zu freuen. Als Gefangener ist man ein Opfer, in Freiheit ein Komplize dieser gro\u00dfen Ungerechtigkeit\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich wei\u00df, dass das Schrecklichste auf der Welt die Begegnung mit demjenigen ist, der die Macht hat, \u00fcber dein Schicksal zu entscheiden. Ich kenne die Qual und Dem\u00fctigung, wenn es dieser Autorit\u00e4t gleichg\u00fcltig ist, was auch immer man sagt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch den Klang einer Fl\u00f6te aus Papier kenne ich. Genauso die unstillbare Sehnsucht, die sie ausdr\u00fccken kann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Altan sah seine erneute Verhaftung kommen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ich wei\u00df auch, dass die M\u00f6glichkeit besteht, wieder verhaftet zu werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Selman besteht diese M\u00f6glichkeit nicht, denn er sitzt nach wie vor in Haft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er ist so alt wie mein Sohn, er macht Hanteln aus Salzverpackungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Niemand kommt ihn besuchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber beschwert er sich nie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er lehnt sich einfach an die Wand und spielt auf seiner Papierfl\u00f6te.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Die Frankfurter Rundschau feiert ihren 75. Geburtstag und macht zu diesem Anlass eine Liste 75 beeindruckender Pers\u00f6nlichkeiten unserer Zeitgeschichte bekannt. Mit seinem unerm\u00fcdlichen Einsatz f\u00fcr Demokratie und Menschenrechte in der T\u00fcrkei hat es der seit mehr als vier Jahren mit einer kleinen Unterbrechung inhaftierte Intellektuelle und Journalist Ahmet Altan auch auf diese Liste geschafft. Seit [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":18653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override":[{"single_blog_custom":"","sidebar":"","second_sidebar":"","share_position":"","share_float_style":"","post_date_format":"","post_date_format_custom":"","post_reading_time_wpm":"","zoom_button_out_step":"1","zoom_button_in_step":"1","number_popup_post":"1"}],"image_override":[{"single_post_thumbnail_size":"","single_post_gallery_size":""}],"trending_post_position":"","trending_post_label":"","sponsored_post_label":"","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":""},"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal"}]},"footnotes":""},"categories":[2868,4680],"tags":[2999,5454,5455],"class_list":["post-18652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlagzeile","category-up-manset","tag-ahmet-altan-de-2","tag-die-frankfurter-rundschau","tag-selman-guelen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists\" \/>\n<meta property=\"og:description\" content=\"Die Frankfurter Rundschau feiert ihren 75. Geburtstag und macht zu diesem Anlass eine Liste 75 beeindruckender Pers\u00f6nlichkeiten unserer Zeitgeschichte bekannt. Mit seinem unerm\u00fcdlichen Einsatz f\u00fcr Demokratie und Menschenrechte in der T\u00fcrkei hat es der seit mehr als vier Jahren mit einer kleinen Unterbrechung inhaftierte Intellektuelle und Journalist Ahmet Altan auch auf diese Liste geschafft. Seit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T19:04:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-22T19:04:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen\",\"datePublished\":\"2020-10-22T19:04:33+00:00\",\"dateModified\":\"2020-10-22T19:04:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/\"},\"wordCount\":1418,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ahmet-altan.jpg\",\"keywords\":[\"ahmet altan\",\"Die Frankfurter Rundschau\",\"Selman G\u00fclen\"],\"articleSection\":[\"Schlagzeile\",\"up-manset\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/\",\"name\":\"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ahmet-altan.jpg\",\"datePublished\":\"2020-10-22T19:04:33+00:00\",\"dateModified\":\"2020-10-22T19:04:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ahmet-altan.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ahmet-altan.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/","og_locale":"de_DE","og_type":"article","og_title":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists","og_description":"Die Frankfurter Rundschau feiert ihren 75. Geburtstag und macht zu diesem Anlass eine Liste 75 beeindruckender Pers\u00f6nlichkeiten unserer Zeitgeschichte bekannt. Mit seinem unerm\u00fcdlichen Einsatz f\u00fcr Demokratie und Menschenrechte in der T\u00fcrkei hat es der seit mehr als vier Jahren mit einer kleinen Unterbrechung inhaftierte Intellektuelle und Journalist Ahmet Altan auch auf diese Liste geschafft. Seit [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2020-10-22T19:04:33+00:00","article_modified_time":"2020-10-22T19:04:40+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen","datePublished":"2020-10-22T19:04:33+00:00","dateModified":"2020-10-22T19:04:40+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/"},"wordCount":1418,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg","keywords":["ahmet altan","Die Frankfurter Rundschau","Selman G\u00fclen"],"articleSection":["Schlagzeile","up-manset"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/","url":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/","name":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg","datePublished":"2020-10-22T19:04:33+00:00","dateModified":"2020-10-22T19:04:40+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/10\/ahmet-altan.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/mut-fuer-die-welt-ahmet-altan-unter-75-ausgewaehlten-personen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"Mut f\u00fcr die Welt: Ahmet Altan unter 75 ausgew\u00e4hlten Personen"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/18652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=18652"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/18652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/18653"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=18652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=18652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=18652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}