{"id":14916,"date":"2020-04-20T21:53:56","date_gmt":"2020-04-20T21:53:56","guid":{"rendered":"http:\/\/internationaljournalists.org\/?p=14916"},"modified":"2020-04-27T21:57:37","modified_gmt":"2020-04-27T21:57:37","slug":"wenn-nicht-wir-wer-wird-es-sagen","status":"publish","type":"post","link":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/","title":{"rendered":"\u201cWenn nicht wir, wer wird es sagen?\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In seiner Rede zum Geschwister-Scholl-Preis spricht sich der Schriftsteller Ahmet Altan gegen Hass und Nationalismus aus &#8211; verfasst in t\u00fcrkischer Haft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a>Wer wird es sagen<\/a>, Wenn wir es nicht, wer wird es sagen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Der t\u00fcrkische Schriftsteller Ahmet Altan hat f\u00fcr sein Buch &#8222;Ich werde die Welt nicht wieder<\/em>sehen&#8220;&nbsp;<em>am Montagabend den&nbsp;<a href=\"https:\/\/www.sueddeutsche.de\/thema\/Geschwister-Scholl-Preis\">Geschwister-Scholl-Preis<\/a>&nbsp;der Stadt M\u00fcnchen bekommen &#8211; eine Ehrung in Abwesenheit, denn Altan sitzt im Gef\u00e4ngnis. Wir dokumentieren die Rede, die er wie sein Buch in der Haft geschrieben und nach M\u00fcnchen geschickt hat.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Leben eines Menschen muss es etwas geben, das wertvoller ist als das Leben selbst. Etwas, das wertvoll genug ist, um sein Leben daf\u00fcr einzusetzen. Seit Ewigkeiten zieht die Menschheit mit einer Unwandelbarkeit dahin, deren Finsternis einer Winternacht gleicht. Eine Ausnahme bilden Menschen, in deren Leben es ein Ziel gibt, f\u00fcr das sie eben dieses Leben einzusetzen bereit sind. Wenn sie in dieser Dunkelheit ein Licht anz\u00fcnden, werden sie selbst sichtbar und werfen dieses Licht auch auf die&nbsp;Unsichtbaren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Beginn des Lebens, die Geburt, bei der aus einem Lebewesen ein anderes Lebewesen hervorgeht, ist ein Wunder. Der Tod mit seiner Unber\u00fchrbarkeit, seiner Unausweichlichkeit und seinem gro\u00dfen, nie zu erforschenden Geheimnis, ist voller Pracht. Das Leben hingegen besteht, im Widerspruch zum Wunder seines Beginns und der W\u00fcrde seines Endes, aus eint\u00f6nigen Wiederholungen. Solange der Mensch seinem Leben nicht etwas hinzuf\u00fcgt, das dieses an Wert \u00fcbersteigt, wird sein Erdenweg nie mehr sein als ein Teil dieser ewigen gew\u00f6hnlichen&nbsp;Wiederholungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit einem allen Lebewesen eigenen Instinkt glauben auch die Menschen, dass es nichts Wichtigeres gibt, als zu leben. Leben &#8211; als was auch immer, wie auch immer. Die gro\u00dfe Mehrheit der Menschen lebt mit diesem Instinkt, sieht in der Bewahrung ihrer Existenz und ihrer Interessen die h\u00f6chste Logik und verschwindet, mit dem Tod zusammen, mit Millionen anderer Lebewesen im&nbsp;Nichts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Hilflos in einer undurchsichtigen Menschenmenge und gefangen in ewiger Finsternis seinem Untergang entgegen zu taumeln, ist furchteinfl\u00f6\u00dfend. Und Furcht gebiert Gewalt. Menschen, die aus ihrem Leben kein Licht hervorbringen k\u00f6nnen, werden zu Feinden dieses ihnen so fremden Lichts. In dieser Feindschaft sehen sie eine Art Rettung, sie klammern sich im Dunkeln aneinander und erkl\u00e4ren ihren Hass auf all jene, die ihnen nicht \u00e4hneln, zur Grundlage ihres&nbsp;Daseins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8222;Sie begreifen nicht, dass sie sich selbst t\u00f6ten, wenn sie das Leben eines anderen Teils der Menschheit ausl\u00f6schen.&#8220;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich glaube, dass diese Furcht und diese Feindschaft Ausl\u00f6ser des Rassismus und Militarismus sind, die heute die gesamte Welt erfasst haben. In Hass und Totschlag sehen diese Menschen einen Ausweg aus ihrer eigenen&nbsp;Ausl\u00f6schung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die von Militarismus und Rassismus infizierten Menschen setzen alles daran, sich &#8211; nach dem Muster sich selbst auffressender Tiere &#8211; auf Kosten der Menschheit zu n\u00e4hren, der sie doch auch angeh\u00f6ren. Sie begreifen nicht, dass sie sich selbst t\u00f6ten, wenn sie das Leben eines anderen Teils der Menschheit&nbsp;ausl\u00f6schen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass Menschen auf ihrem in einem Winkel des unendlichen Weltalls isolierten Planeten die kurze Spanne ihrer Lebenszeit daf\u00fcr einsetzen, ihr eigenes Selbst zu erh\u00f6hen und andere Menschen ihre \u00dcberlegenheit sp\u00fcren zu lassen, bringt letztendlich allen nichts als Unheil. Der auf dem finsteren Weg ins Nichts empfundene Hass dient lediglich dazu, die Sinnlosigkeit dieser Finsternis noch zu&nbsp;verst\u00e4rken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich muss zugeben, dass ich hin und wieder dem Wunsch nachzugeben bereit bin, wie ein trotziges Kind zu schreien: &#8222;Wir werden alle sterben!&#8220; W\u00fcrden vom heutigen Tage an alle Geburten gestoppt, w\u00e4re dieser sonderbare Planet nach h\u00f6chstens 90 Jahren menschenleer. Ist es da nicht unsinnig, dass eine derart hilflose Spezies unter den Lebewesen sich einer gegen\u00fcber dem anderen als \u00fcberlegen&nbsp;behauptet?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Erschaffung des Menschen war wohl ein wenig Eile am Werk; es kam ein Lebewesen hervor, in dem etliche miteinander unvereinbare Gef\u00fchle eng beieinander liegen. Wie Mitleid und Hass, G\u00fcte und B\u00f6sartigkeit gedeihen Klugheit und Dummheit nebeneinander in gleicher&nbsp;Erscheinungsform.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Nationalismus, Hass, Schlechtigkeit und Dummheit in angereichertem Ma\u00dfe zusammenfinden, entsteht eine toxische Mischung. Gegen diese t\u00f6dliche Krankheit wirken als Gegengift Mitleid, G\u00fcte und Klugheit, doch muss auch der h\u00e4sslichen Fratze des Nationalismus die Maske der Heiligkeit abgerissen werden, hinter der dieser sich&nbsp;versteckt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8222;Kein menschliches Leben endet gl\u00fccklich, denn am Ende steht immer der Tod.&#8220;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In unseren Tagen, in denen die Fahnen, M\u00e4rsche, Waffen und Gewalttaten des Rassismus und Militarismus erneut die Menschheit beschmutzen, kann man es nicht laut genug ausrufen, dass das gemeinsame Wohl der Menschheit nicht in ihrer Spaltung, sondern in ihrer Einheit&nbsp;liegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kein menschliches Leben endet gl\u00fccklich, denn am Ende steht immer der Tod. Was soll es dem Menschen da bringen, sein so oder so ungl\u00fccklich endendes, meistens auch unbedeutendes Leben mit Hass zu&nbsp;vergiften?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn wir nicht jetzt zur Sprache bringen, dass dieses niemandem n\u00fctzt, wann denn sonst? Und wer wird dies aussprechen, wenn wir es nicht tun? Wollen wir denn nicht wahrhaben, dass es f\u00fcr alle von uns eine &#8222;erf\u00fcllende Verpflichtung&#8220; gibt, n\u00e4mlich aufzustehen und f\u00fcr das Wohl der Menschheit zu k\u00e4mpfen, die Wahrheit zu verk\u00fcnden und so unser Leben mit etwas zu bereichern, das dieses an Wert&nbsp;\u00fcbersteigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vergessen wir auch nicht, dass im Augenblick des Todes jeder in jenem &#8222;Leben&#8220; genannten kurzen Zeitabschnitt versp\u00fcrte Wunsch, jeder \u00c4rger, jedes Streben, jeder Profitwettkampf seine Bedeutung verliert, ja sogar l\u00e4cherlich&nbsp;wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8222;Diese Rede schreibe ich im Gef\u00e4ngnis. Deswegen kann ich heute nicht unter Ihnen sein.&#8220;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lebensl\u00e4ufe, denen der Tod nicht den Sinn rauben kann, sind eher selten. Denn nur jene Menschen, die ihrem Leben etwas hinzuf\u00fcgen, das dieses an Wert \u00fcbertrifft, k\u00f6nnen der Macht des Todes die Stirn bieten und vom Tod selbst nicht der L\u00e4cherlichkeit preisgegeben werden. Sie haben sich heute hier zusammengefunden, um der Verleihung eines Preises beizuwohnen, der den Namen zweier junger Menschen tr\u00e4gt, die der Tod nicht bagatellisieren konnte, weil es in ihrem kurzen Leben einen Wert gab, der f\u00fcr sie den Wert ihres Lebens&nbsp;\u00fcbertraf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Leben anderer Menschen zu retten, gegen die von diesen Menschen erlittene Unterdr\u00fcckung zu protestieren und erschreckender Ungerechtigkeit Einhalt zu gebieten, waren Werte, die die Geschwister Scholl h\u00f6her einsch\u00e4tzten als ihr eigenes Leben. Mit ihren Schriften widerstanden sie Waffen und Gewalt. Bis heute bilden sie ein Vorbild. Ihre Flugbl\u00e4tter lehrten einen blutigen Despoten das F\u00fcrchten, der \u00fcber Gesch\u00fctze, Panzer und Bomben&nbsp;verf\u00fcgte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese beiden jungen Menschen zeigten uns nicht nur, wie ein Leben sich dem Tod gegen\u00fcber kraftvoll beweisen kann, sie machten uns auch klar, welche bedeutungsvolle Widerstands- und Lebensform das geschriebene Wort&nbsp;darstellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass Sie mein Buch f\u00fcr Wert hielten, mit dem nach diesen beiden jungen Menschen benannten Preis ausgezeichnet zu werden, erfuhr ich in einer Gef\u00e4ngniszelle. Auch diese Rede schreibe ich im Gef\u00e4ngnis. Deswegen kann ich heute nicht unter Ihnen&nbsp;sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Preis hat einen Teil der diesen beiden \u00fcberragenden Menschen innewohnenden Kraft auch auf mein Leben \u00fcbertragen und damit meine Widerstandskraft innerhalb dieser Mauern gest\u00e4rkt. Ich bin \u00fcberzeugt, dass die Erinnerung an die Geschwister Scholl auch Ihren Widerstand gegen nationalistische Str\u00f6mungen best\u00e4rken&nbsp;wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daf\u00fcr, dass Sie mich zu einem Teil zweier Leben machten, die mit dem Tod nicht der Vergessenheit anheimfielen, m\u00f6chte ich Ihnen allen von Herzen danken. Noch einmal haben Sie mir best\u00e4tigt, dass die&nbsp;<a href=\"https:\/\/www.sueddeutsche.de\/thema\/Literatur\">Literatur<\/a>&nbsp;m\u00e4chtiger ist als die&nbsp;Tyrannei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle: <a href=\"https:\/\/www.sueddeutsche.de\/\">https:\/\/www.sueddeutsche.de\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In seiner Rede zum Geschwister-Scholl-Preis spricht sich der Schriftsteller Ahmet Altan gegen Hass und Nationalismus aus &#8211; verfasst in t\u00fcrkischer Haft. Wer wird es sagen, Wenn wir es nicht, wer wird es sagen? Der t\u00fcrkische Schriftsteller Ahmet Altan hat f\u00fcr sein Buch &#8222;Ich werde die Welt nicht wiedersehen&#8220;&nbsp;am Montagabend den&nbsp;Geschwister-Scholl-Preis&nbsp;der Stadt M\u00fcnchen bekommen &#8211; eine [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":14917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jf_save_progress":"","_jf_limit_responses":"","jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override":[{"single_blog_custom":"","sidebar":"","second_sidebar":"","share_position":"","share_float_style":"","post_date_format":"","post_date_format_custom":"","post_reading_time_wpm":"","zoom_button_out_step":"1","zoom_button_in_step":"1","number_popup_post":"1"}],"image_override":[{"single_post_thumbnail_size":"","single_post_gallery_size":""}],"trending_post_position":"","trending_post_label":"","sponsored_post_label":"","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":""},"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal"}]},"footnotes":""},"categories":[4630,4680],"tags":[4708],"class_list":["post-14916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inhaftierte-journalisten","category-up-manset","tag-sueddeutsche-zeitung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists\" \/>\n<meta property=\"og:description\" content=\"In seiner Rede zum Geschwister-Scholl-Preis spricht sich der Schriftsteller Ahmet Altan gegen Hass und Nationalismus aus &#8211; verfasst in t\u00fcrkischer Haft. Wer wird es sagen, Wenn wir es nicht, wer wird es sagen? Der t\u00fcrkische Schriftsteller Ahmet Altan hat f\u00fcr sein Buch &#8222;Ich werde die Welt nicht wiedersehen&#8220;&nbsp;am Montagabend den&nbsp;Geschwister-Scholl-Preis&nbsp;der Stadt M\u00fcnchen bekommen &#8211; eine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ijaev.org\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-20T21:53:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-27T21:57:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:site\" content=\"@journalists_tr\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\"},\"headline\":\"\u201cWenn nicht wir, wer wird es sagen?\u201d\",\"datePublished\":\"2020-04-20T21:53:56+00:00\",\"dateModified\":\"2020-04-27T21:57:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/\"},\"wordCount\":1288,\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ahmet-altan-biz-degilsek-kim.jpg\",\"keywords\":[\"s\u00fcddeutsche zeitung\"],\"articleSection\":[\"Inhaftierte Journalisten\",\"up-manset\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/\",\"name\":\"\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ahmet-altan-biz-degilsek-kim.jpg\",\"datePublished\":\"2020-04-20T21:53:56+00:00\",\"dateModified\":\"2020-04-27T21:57:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ahmet-altan-biz-degilsek-kim.jpg\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ahmet-altan-biz-degilsek-kim.jpg\",\"width\":299,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/wenn-nicht-wir-wer-wird-es-sagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cWenn nicht wir, wer wird es sagen?\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"name\":\"International Journalists\",\"description\":\"International Journalists\",\"publisher\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#organization\",\"name\":\"International Journalists Association e.V.\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"contentUrl\":\"https:\\\/\\\/internationaljournalists.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/LOGO-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"International Journalists Association e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ijaev.org\",\"https:\\\/\\\/x.com\\\/journalists_tr\",\"https:\\\/\\\/x.com\\\/journalists_EN\",\"https:\\\/\\\/x.com\\\/journalists_de\",\"https:\\\/\\\/www.instagram.com\\\/international_journalists\\\/?hl=de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/#\\\/schema\\\/person\\\/1007acacd3e1b8fc5067b5fd3b4c86c3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/internationaljournalists.org\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/internationaljournalists\"],\"url\":\"https:\\\/\\\/internationaljournalists.org\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/","og_locale":"de_DE","og_type":"article","og_title":"\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists","og_description":"In seiner Rede zum Geschwister-Scholl-Preis spricht sich der Schriftsteller Ahmet Altan gegen Hass und Nationalismus aus &#8211; verfasst in t\u00fcrkischer Haft. Wer wird es sagen, Wenn wir es nicht, wer wird es sagen? Der t\u00fcrkische Schriftsteller Ahmet Altan hat f\u00fcr sein Buch &#8222;Ich werde die Welt nicht wiedersehen&#8220;&nbsp;am Montagabend den&nbsp;Geschwister-Scholl-Preis&nbsp;der Stadt M\u00fcnchen bekommen &#8211; eine [&hellip;]","og_url":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/","og_site_name":"International Journalists","article_publisher":"https:\/\/www.facebook.com\/ijaev.org","article_published_time":"2020-04-20T21:53:56+00:00","article_modified_time":"2020-04-27T21:57:37+00:00","og_image":[{"width":299,"height":168,"url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@journalists_tr","twitter_site":"@journalists_tr","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#article","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/"},"author":{"name":"admin","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3"},"headline":"\u201cWenn nicht wir, wer wird es sagen?\u201d","datePublished":"2020-04-20T21:53:56+00:00","dateModified":"2020-04-27T21:57:37+00:00","mainEntityOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/"},"wordCount":1288,"publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg","keywords":["s\u00fcddeutsche zeitung"],"articleSection":["Inhaftierte Journalisten","up-manset"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/","url":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/","name":"\u201cWenn nicht wir, wer wird es sagen?\u201d - International Journalists","isPartOf":{"@id":"https:\/\/internationaljournalists.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#primaryimage"},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#primaryimage"},"thumbnailUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg","datePublished":"2020-04-20T21:53:56+00:00","dateModified":"2020-04-27T21:57:37+00:00","breadcrumb":{"@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#primaryimage","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2020\/04\/ahmet-altan-biz-degilsek-kim.jpg","width":299,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/internationaljournalists.org\/de\/wenn-nicht-wir-wer-wird-es-sagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/internationaljournalists.org\/de\/"},{"@type":"ListItem","position":2,"name":"\u201cWenn nicht wir, wer wird es sagen?\u201d"}]},{"@type":"WebSite","@id":"https:\/\/internationaljournalists.org\/de\/#website","url":"https:\/\/internationaljournalists.org\/de\/","name":"International Journalists","description":"International Journalists","publisher":{"@id":"https:\/\/internationaljournalists.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationaljournalists.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/internationaljournalists.org\/de\/#organization","name":"International Journalists Association e.V.","url":"https:\/\/internationaljournalists.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","contentUrl":"https:\/\/internationaljournalists.org\/wp-content\/uploads\/2025\/09\/LOGO-scaled.png","width":2560,"height":1440,"caption":"International Journalists Association e.V."},"image":{"@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ijaev.org","https:\/\/x.com\/journalists_tr","https:\/\/x.com\/journalists_EN","https:\/\/x.com\/journalists_de","https:\/\/www.instagram.com\/international_journalists\/?hl=de"]},{"@type":"Person","@id":"https:\/\/internationaljournalists.org\/de\/#\/schema\/person\/1007acacd3e1b8fc5067b5fd3b4c86c3","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0d25691a3360deb6cc936e5973f6121b8ac52261979241132cefbbdbc80e71?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/internationaljournalists.org","http:\/\/www.youtube.com\/c\/internationaljournalists"],"url":"https:\/\/internationaljournalists.org\/de\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/14916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/comments?post=14916"}],"version-history":[{"count":0,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/posts\/14916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media\/14917"}],"wp:attachment":[{"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/media?parent=14916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/categories?post=14916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internationaljournalists.org\/de\/wp-json\/wp\/v2\/tags?post=14916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}